{"id":29021,"date":"2019-07-27T07:19:47","date_gmt":"2019-07-27T06:19:47","guid":{"rendered":"https:\/\/vin-beta.mecalife.com\/auto\/finition-dacia-lodgy-2012-2019\/"},"modified":"2019-07-27T07:19:47","modified_gmt":"2019-07-27T06:19:47","slug":"finition-dacia-lodgy-2012-2019","status":"publish","type":"auto","link":"https:\/\/vin.mecalife.com\/it_it\/auto\/finition-dacia-lodgy-2012-2019\/","title":{"rendered":"DACIA LODGY 2012 2019 Finitura"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"29021\" class=\"elementor elementor-29021\" data-elementor-post-type=\"auto\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-599537a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"599537a\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;sticky&quot;:&quot;top&quot;,&quot;animation&quot;:&quot;none&quot;,&quot;sticky_on&quot;:[&quot;desktop&quot;],&quot;sticky_offset&quot;:0,&quot;sticky_effects_offset&quot;:0}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-75c806e\" data-id=\"75c806e\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bf09292 elementor-widget elementor-widget-theme-site-logo elementor-widget-image\" data-id=\"bf09292\" data-element_type=\"widget\" data-widget_type=\"theme-site-logo.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.22.0 - 26-06-2024 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t<a href=\"https:\/\/vin.mecalife.com\/it_it\">\n\t\t\t<img decoding=\"async\" width=\"200\" height=\"56\" src=\"https:\/\/vin.mecalife.com\/wp-content\/uploads\/2020\/06\/mecavin_logo.svg\" class=\"attachment-full size-full wp-image-20885\" alt=\"\" \/>\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cd865e5 elementor-headline--style-rotate elementor-hidden-mobile elementor-widget elementor-widget-animated-headline\" data-id=\"cd865e5\" data-element_type=\"widget\" data-settings=\"{&quot;headline_style&quot;:&quot;rotate&quot;,&quot;animation_type&quot;:&quot;flip&quot;,&quot;rotating_text&quot;:&quot;l\\u2019immatriculation\\nle code VIN&quot;,&quot;loop&quot;:&quot;yes&quot;,&quot;rotate_iteration_delay&quot;:2500}\" data-widget_type=\"animated-headline.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/vin.mecalife.com\/wp-content\/plugins\/elementor-pro\/assets\/css\/widget-animated-headline.min.css\">\t\t<h1 class=\"elementor-headline elementor-headline-animation-type-flip\">\n\t\t\t\t\t<span class=\"elementor-headline-plain-text elementor-headline-text-wrapper\">Trovare finiture e attrezzature <\/br> DACIA LODGY con<\/span>\n\t\t\t\t<span class=\"elementor-headline-dynamic-wrapper elementor-headline-text-wrapper\">\n\t\t\t\t\t<span class=\"elementor-headline-dynamic-text elementor-headline-text-active\">\n\t\t\t\tregistrazione\t\t\t<\/span>\n\t\t\t\t\t<span class=\"elementor-headline-dynamic-text\">\n\t\t\t\til codice VIN\t\t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t<\/h1>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-359d53c elementor-hidden-mobile\" data-id=\"359d53c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2dcc0aa elementor-widget elementor-widget-template\" data-id=\"2dcc0aa\" data-element_type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"section\" data-elementor-id=\"28233\" class=\"elementor elementor-28233\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-21cdd55 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"21cdd55\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-96c8fc8\" data-id=\"96c8fc8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-35c7f9e elementor-widget elementor-widget-heading\" data-id=\"35c7f9e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.22.0 - 26-06-2024 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"tel:05 82 28 84 60\">05 82 28 84 60<\/a><\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-fae4bcd\" data-id=\"fae4bcd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bdbce7c elementor-view-stacked elementor-shape-square elementor-widget elementor-widget-icon\" data-id=\"bdbce7c\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"#elementor-action:action=popup:open&settings=eyJpZCI6IjIyOTg0IiwidG9nZ2xlIjpmYWxzZX0=\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-align-justify\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M432 416H16a16 16 0 0 0-16 16v32a16 16 0 0 0 16 16h416a16 16 0 0 0 16-16v-32a16 16 0 0 0-16-16zm0-128H16a16 16 0 0 0-16 16v32a16 16 0 0 0 16 16h416a16 16 0 0 0 16-16v-32a16 16 0 0 0-16-16zm0-128H16a16 16 0 0 0-16 16v32a16 16 0 0 0 16 16h416a16 16 0 0 0 16-16v-32a16 16 0 0 0-16-16zm0-128H16A16 16 0 0 0 0 48v32a16 16 0 0 0 16 16h416a16 16 0 0 0 16-16V48a16 16 0 0 0-16-16z\"><\/path><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a782852 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"a782852\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8b766ef\" data-id=\"8b766ef\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4fe73ac elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4fe73ac\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-custom\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-05b15f8\" data-id=\"05b15f8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-11af5eb elementor-widget elementor-widget-heading\" data-id=\"11af5eb\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Trova la finitura<br>\ne attrezzature \n<br><span style=\"color:#19D180;\">DACIA LODGY<\/span><\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-20e2586 elementor-widget elementor-widget-heading\" data-id=\"20e2586\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">con la registrazione<br>\no il numero di serie del VIN<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5f5404d elementor-hidden-mobile elementor-widget elementor-widget-template\" data-id=\"5f5404d\" data-element_type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"section\" data-elementor-id=\"23245\" class=\"elementor elementor-23245\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-aeda324 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"aeda324\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1c577d5\" data-id=\"1c577d5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-9351f54 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"9351f54\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1b8af4e\" data-id=\"1b8af4e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8f0ce70 elementor-widget elementor-widget-image\" data-id=\"8f0ce70\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/vin.mecalife.com\/wp-content\/uploads\/2021\/09\/mecavin_google_g.svg\" class=\"attachment-full size-full wp-image-20950\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-afb8ae9\" data-id=\"afb8ae9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7c05ec8 elementor-widget elementor-widget-shortcode\" data-id=\"7c05ec8\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-shortcode\"><div id=\"google-business-reviews-rating\" class=\"google-business-reviews-rating gmbrr\">\r\n\t<p class=\"rating\"><span class=\"number\">4,6<\/span> <span class=\"all-stars\"><span class=\"star\"><\/span><span class=\"star\"><\/span><span class=\"star\"><\/span><span class=\"star\"><\/span><span class=\"star split-60-40\"><\/span><\/span> <\/p>\r\n<\/div>\r\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1693f58 elementor-widget elementor-widget-shortcode\" data-id=\"1693f58\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-shortcode\"><span style=\"color:#FFFFFF;\"> sur 1744 Avis Google<\/span><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-56f2345\" data-id=\"56f2345\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9fe5d03 elementor-widget elementor-widget-template\" data-id=\"9fe5d03\" data-element_type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"section\" data-elementor-id=\"25262\" class=\"elementor elementor-25262\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1a0b59d elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"1a0b59d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9ffe24c\" data-id=\"9ffe24c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0ed2715 elementor-align-left elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"0ed2715\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/vin.mecalife.com\/wp-content\/plugins\/elementor\/assets\/css\/widget-icon-list.min.css\">\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256c0 136.967-111.033 248-248 248S8 392.967 8 256 119.033 8 256 8s248 111.033 248 248zM227.314 387.314l184-184c6.248-6.248 6.248-16.379 0-22.627l-22.627-22.627c-6.248-6.249-16.379-6.249-22.628 0L216 308.118l-70.059-70.059c-6.248-6.248-16.379-6.248-22.628 0l-22.627 22.627c-6.248 6.248-6.248 16.379 0 22.627l104 104c6.249 6.249 16.379 6.249 22.628.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Marchio<\/b>, <b>Modello<\/b> e <b>Finitura esatta<\/b><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256c0 136.967-111.033 248-248 248S8 392.967 8 256 119.033 8 256 8s248 111.033 248 248zM227.314 387.314l184-184c6.248-6.248 6.248-16.379 0-22.627l-22.627-22.627c-6.248-6.249-16.379-6.249-22.628 0L216 308.118l-70.059-70.059c-6.248-6.248-16.379-6.248-22.628 0l-22.627 22.627c-6.248 6.248-6.248 16.379 0 22.627l104 104c6.249 6.249 16.379 6.249 22.628.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Elenco preciso<\/b> e <b>Dettagli delle opzioni<\/b><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256c0 136.967-111.033 248-248 248S8 392.967 8 256 119.033 8 256 8s248 111.033 248 248zM227.314 387.314l184-184c6.248-6.248 6.248-16.379 0-22.627l-22.627-22.627c-6.248-6.249-16.379-6.249-22.628 0L216 308.118l-70.059-70.059c-6.248-6.248-16.379-6.248-22.628 0l-22.627 22.627c-6.248 6.248-6.248 16.379 0 22.627l104 104c6.249 6.249 16.379 6.249 22.628.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Tariffa<\/b> di ogni <b>Opzione<\/b><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256c0 136.967-111.033 248-248 248S8 392.967 8 256 119.033 8 256 8s248 111.033 248 248zM227.314 387.314l184-184c6.248-6.248 6.248-16.379 0-22.627l-22.627-22.627c-6.248-6.249-16.379-6.249-22.628 0L216 308.118l-70.059-70.059c-6.248-6.248-16.379-6.248-22.628 0l-22.627 22.627c-6.248 6.248-6.248 16.379 0 22.627l104 104c6.249 6.249 16.379 6.249 22.628.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Elenco<\/b> di <b>Equipaggiamento standard<\/b><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256c0 136.967-111.033 248-248 248S8 392.967 8 256 119.033 8 256 8s248 111.033 248 248zM227.314 387.314l184-184c6.248-6.248 6.248-16.379 0-22.627l-22.627-22.627c-6.248-6.249-16.379-6.249-22.628 0L216 308.118l-70.059-70.059c-6.248-6.248-16.379-6.248-22.628 0l-22.627 22.627c-6.248 6.248-6.248 16.379 0 22.627l104 104c6.249 6.249 16.379 6.249 22.628.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Motorizzazione<\/b>, <b>Spostamento<\/b>, <b>Potenza<\/b><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256c0 136.967-111.033 248-248 248S8 392.967 8 256 119.033 8 256 8s248 111.033 248 248zM227.314 387.314l184-184c6.248-6.248 6.248-16.379 0-22.627l-22.627-22.627c-6.248-6.249-16.379-6.249-22.628 0L216 308.118l-70.059-70.059c-6.248-6.248-16.379-6.248-22.628 0l-22.627 22.627c-6.248 6.248-6.248 16.379 0 22.627l104 104c6.249 6.249 16.379 6.249 22.628.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Tipo <b>Cambio <\/b> e tipo di <b>Trasmissione<\/b><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256c0 136.967-111.033 248-248 248S8 392.967 8 256 119.033 8 256 8s248 111.033 248 248zM227.314 387.314l184-184c6.248-6.248 6.248-16.379 0-22.627l-22.627-22.627c-6.248-6.249-16.379-6.249-22.628 0L216 308.118l-70.059-70.059c-6.248-6.248-16.379-6.248-22.628 0l-22.627 22.627c-6.248 6.248-6.248 16.379 0 22.627l104 104c6.249 6.249 16.379 6.249 22.628.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Paese di origine<\/b> & <b>Data di produzione<\/b><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256c0 136.967-111.033 248-248 248S8 392.967 8 256 119.033 8 256 8s248 111.033 248 248zM227.314 387.314l184-184c6.248-6.248 6.248-16.379 0-22.627l-22.627-22.627c-6.248-6.249-16.379-6.249-22.628 0L216 308.118l-70.059-70.059c-6.248-6.248-16.379-6.248-22.628 0l-22.627 22.627c-6.248 6.248-6.248 16.379 0 22.627l104 104c6.249 6.249 16.379 6.249 22.628.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Codice<\/b> , <b>Nome<\/b> Tipo <b>Pittura esterna<\/b><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256c0 136.967-111.033 248-248 248S8 392.967 8 256 119.033 8 256 8s248 111.033 248 248zM227.314 387.314l184-184c6.248-6.248 6.248-16.379 0-22.627l-22.627-22.627c-6.248-6.249-16.379-6.249-22.628 0L216 308.118l-70.059-70.059c-6.248-6.248-16.379-6.248-22.628 0l-22.627 22.627c-6.248 6.248-6.248 16.379 0 22.627l104 104c6.249 6.249 16.379 6.249 22.628.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Codice<\/b> , <b>Nome<\/b> Tipo <b>Rivestimento interno<\/b><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256c0 136.967-111.033 248-248 248S8 392.967 8 256 119.033 8 256 8s248 111.033 248 248zM227.314 387.314l184-184c6.248-6.248 6.248-16.379 0-22.627l-22.627-22.627c-6.248-6.249-16.379-6.249-22.628 0L216 308.118l-70.059-70.059c-6.248-6.248-16.379-6.248-22.628 0l-22.627 22.627c-6.248 6.248-6.248 16.379 0 22.627l104 104c6.249 6.249 16.379 6.249 22.628.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Prezzo del veicolo nuovo<\/b> + <b>Prezzo totale dell'opzione<\/b><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-4396830 elementor-widget elementor-widget-template\" data-id=\"4396830\" data-element_type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"section\" data-elementor-id=\"28113\" class=\"elementor elementor-28113\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-24b8376 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"24b8376\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-68f5b62\" data-id=\"68f5b62\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4cd3ee2 elementor-button-align-end elementor-widget elementor-widget-form\" data-id=\"4cd3ee2\" data-element_type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;Suivant&quot;,&quot;step_previous_label&quot;:&quot;Pr\\u00e9c\\u00e9dent&quot;,&quot;step_type&quot;:&quot;none&quot;,&quot;button_width&quot;:&quot;100&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor-pro - v3.22.0 - 24-06-2024 *\/\n.elementor-button.elementor-hidden,.elementor-hidden{display:none}.e-form__step{width:100%}.e-form__step:not(.elementor-hidden){display:flex;flex-wrap:wrap}.e-form__buttons{flex-wrap:wrap}.e-form__buttons,.e-form__buttons__wrapper{display:flex}.e-form__indicators{display:flex;justify-content:space-between;align-items:center;flex-wrap:nowrap;font-size:13px;margin-bottom:var(--e-form-steps-indicators-spacing)}.e-form__indicators__indicator{display:flex;flex-direction:column;align-items:center;justify-content:center;flex-basis:0;padding:0 var(--e-form-steps-divider-gap)}.e-form__indicators__indicator__progress{width:100%;position:relative;background-color:var(--e-form-steps-indicator-progress-background-color);border-radius:var(--e-form-steps-indicator-progress-border-radius);overflow:hidden}.e-form__indicators__indicator__progress__meter{width:var(--e-form-steps-indicator-progress-meter-width,0);height:var(--e-form-steps-indicator-progress-height);line-height:var(--e-form-steps-indicator-progress-height);padding-right:15px;border-radius:var(--e-form-steps-indicator-progress-border-radius);background-color:var(--e-form-steps-indicator-progress-color);color:var(--e-form-steps-indicator-progress-meter-color);text-align:right;transition:width .1s linear}.e-form__indicators__indicator:first-child{padding-left:0}.e-form__indicators__indicator:last-child{padding-right:0}.e-form__indicators__indicator--state-inactive{color:var(--e-form-steps-indicator-inactive-primary-color,#c2cbd2)}.e-form__indicators__indicator--state-inactive [class*=indicator--shape-]:not(.e-form__indicators__indicator--shape-none){background-color:var(--e-form-steps-indicator-inactive-secondary-color,#fff)}.e-form__indicators__indicator--state-inactive object,.e-form__indicators__indicator--state-inactive svg{fill:var(--e-form-steps-indicator-inactive-primary-color,#c2cbd2)}.e-form__indicators__indicator--state-active{color:var(--e-form-steps-indicator-active-primary-color,#39b54a);border-color:var(--e-form-steps-indicator-active-secondary-color,#fff)}.e-form__indicators__indicator--state-active [class*=indicator--shape-]:not(.e-form__indicators__indicator--shape-none){background-color:var(--e-form-steps-indicator-active-secondary-color,#fff)}.e-form__indicators__indicator--state-active object,.e-form__indicators__indicator--state-active svg{fill:var(--e-form-steps-indicator-active-primary-color,#39b54a)}.e-form__indicators__indicator--state-completed{color:var(--e-form-steps-indicator-completed-secondary-color,#fff)}.e-form__indicators__indicator--state-completed [class*=indicator--shape-]:not(.e-form__indicators__indicator--shape-none){background-color:var(--e-form-steps-indicator-completed-primary-color,#39b54a)}.e-form__indicators__indicator--state-completed .e-form__indicators__indicator__label{color:var(--e-form-steps-indicator-completed-primary-color,#39b54a)}.e-form__indicators__indicator--state-completed .e-form__indicators__indicator--shape-none{color:var(--e-form-steps-indicator-completed-primary-color,#39b54a);background-color:initial}.e-form__indicators__indicator--state-completed object,.e-form__indicators__indicator--state-completed svg{fill:var(--e-form-steps-indicator-completed-secondary-color,#fff)}.e-form__indicators__indicator__icon{width:var(--e-form-steps-indicator-padding,30px);height:var(--e-form-steps-indicator-padding,30px);font-size:var(--e-form-steps-indicator-icon-size);border-width:1px;border-style:solid;display:flex;justify-content:center;align-items:center;overflow:hidden;margin-bottom:10px}.e-form__indicators__indicator__icon img,.e-form__indicators__indicator__icon object,.e-form__indicators__indicator__icon svg{width:var(--e-form-steps-indicator-icon-size);height:auto}.e-form__indicators__indicator__icon .e-font-icon-svg{height:1em}.e-form__indicators__indicator__number{width:var(--e-form-steps-indicator-padding,30px);height:var(--e-form-steps-indicator-padding,30px);border-width:1px;border-style:solid;display:flex;justify-content:center;align-items:center;margin-bottom:10px}.e-form__indicators__indicator--shape-circle{border-radius:50%}.e-form__indicators__indicator--shape-square{border-radius:0}.e-form__indicators__indicator--shape-rounded{border-radius:5px}.e-form__indicators__indicator--shape-none{border:0}.e-form__indicators__indicator__label{text-align:center}.e-form__indicators__indicator__separator{width:100%;height:var(--e-form-steps-divider-width);background-color:#babfc5}.e-form__indicators--type-icon,.e-form__indicators--type-icon_text,.e-form__indicators--type-number,.e-form__indicators--type-number_text{align-items:flex-start}.e-form__indicators--type-icon .e-form__indicators__indicator__separator,.e-form__indicators--type-icon_text .e-form__indicators__indicator__separator,.e-form__indicators--type-number .e-form__indicators__indicator__separator,.e-form__indicators--type-number_text .e-form__indicators__indicator__separator{margin-top:calc(var(--e-form-steps-indicator-padding, 30px) \/ 2 - var(--e-form-steps-divider-width, 1px) \/ 2)}.elementor-field-type-hidden{display:none}.elementor-field-type-html{display:inline-block}.elementor-field-type-tel input{direction:inherit}.elementor-login .elementor-lost-password,.elementor-login .elementor-remember-me{font-size:.85em}.elementor-field-type-recaptcha_v3 .elementor-field-label{display:none}.elementor-field-type-recaptcha_v3 .grecaptcha-badge{z-index:1}.elementor-button .elementor-form-spinner{order:3}.elementor-form .elementor-button .elementor-button-content-wrapper{align-items:center}.elementor-form .elementor-button .elementor-button-text{white-space:normal}.elementor-form .elementor-button svg{height:auto}.elementor-form .elementor-button .e-font-icon-svg{height:1em}.elementor-form .elementor-button .elementor-button-content-wrapper{gap:5px}.elementor-form .elementor-button .elementor-button-icon,.elementor-form .elementor-button .elementor-button-text{flex-grow:unset;order:unset}.elementor-select-wrapper .select-caret-down-wrapper{position:absolute;top:50%;transform:translateY(-50%);inset-inline-end:10px;pointer-events:none;font-size:11px}.elementor-select-wrapper .select-caret-down-wrapper svg{display:unset;width:1em;aspect-ratio:unset;fill:currentColor}.elementor-select-wrapper .select-caret-down-wrapper i{font-size:19px;line-height:2}.elementor-select-wrapper.remove-before:before{content:\"\"!important}<\/style>\t\t<form class=\"elementor-form\" method=\"post\" name=\"Nouveau formulaire\" action=\"\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"28113\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"4cd3ee2\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"MecaVIN FR\" \/>\n\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-hidden elementor-field-group elementor-column elementor-field-group-idaff elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"hidden\" name=\"form_fields[idaff]\" id=\"form-field-idaff\" class=\"elementor-field elementor-size-xs  elementor-field-textual\" value=\"3\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-hidden elementor-field-group elementor-column elementor-field-group-src elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"hidden\" name=\"form_fields[src]\" id=\"form-field-src\" class=\"elementor-field elementor-size-xs  elementor-field-textual\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text\">\n\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[field_11a3bf9]\" id=\"form-field-field_11a3bf9\" class=\"elementor-field elementor-size-xs\" style=\"display:none !important;\">\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button class=\"elementor-button elementor-size-lg\" type=\"submit\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Ottenere il rapporto MecaVIN<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<input type=\"hidden\" name=\"trp-form-language\" value=\"it_it\"\/><\/form>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-09b2b69\" data-id=\"09b2b69\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3311a48 elementor-align-left elementor-mobile-align-justify elementor-widget elementor-widget-button\" data-id=\"3311a48\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xs\" href=\"https:\/\/drive.google.com\/file\/d\/1Umx83Fqmwuq5dzKP6yL228pQ5_Y9DGzW\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">CAMPIONE DEL RAPPORTO<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ad82829 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ad82829\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-cf83d72\" data-id=\"cf83d72\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-59874ad elementor-button-align-end elementor-widget elementor-widget-form\" data-id=\"59874ad\" data-element_type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;Suivant&quot;,&quot;step_previous_label&quot;:&quot;Pr\\u00e9c\\u00e9dent&quot;,&quot;step_type&quot;:&quot;none&quot;,&quot;button_width&quot;:&quot;100&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" name=\"Nouveau formulaire\" action=\"\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"28113\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"59874ad\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"MecaVIN FR\" \/>\n\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-hidden elementor-field-group elementor-column elementor-field-group-idaff elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"hidden\" name=\"form_fields[idaff]\" id=\"form-field-idaff\" class=\"elementor-field elementor-size-xs  elementor-field-textual\" value=\"3\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-hidden elementor-field-group elementor-column elementor-field-group-src elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"hidden\" name=\"form_fields[src]\" id=\"form-field-src\" class=\"elementor-field elementor-size-xs  elementor-field-textual\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text\">\n\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[field_11a3bf9]\" id=\"form-field-field_11a3bf9\" class=\"elementor-field elementor-size-xs\" style=\"display:none !important;\">\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button class=\"elementor-button elementor-size-lg\" type=\"submit\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">OTTENERE IL RAPPORTO<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<input type=\"hidden\" name=\"trp-form-language\" value=\"it_it\"\/><\/form>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-320c00a\" data-id=\"320c00a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-69af977 elementor-align-left elementor-mobile-align-justify elementor-widget elementor-widget-button\" data-id=\"69af977\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xs\" href=\"https:\/\/vin.mecalife.com\/it_it\/esempio-di-rapporto\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Esempio di rapporto<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e35d4ab elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"e35d4ab\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3d03fdc\" data-id=\"3d03fdc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9cb9a08 elementor-widget elementor-widget-template\" data-id=\"9cb9a08\" data-element_type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"section\" data-elementor-id=\"23357\" class=\"elementor elementor-23357\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-588b6af elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"588b6af\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-73452ae\" data-id=\"73452ae\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7158a6b elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-template\" data-id=\"7158a6b\" data-element_type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"section\" data-elementor-id=\"28146\" class=\"elementor elementor-28146\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-43ed6a6 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"43ed6a6\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0842933\" data-id=\"0842933\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b2fcd9f elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"b2fcd9f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-27e54b3\" data-id=\"27e54b3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5ca63b9 elementor-widget elementor-widget-image\" data-id=\"5ca63b9\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/vin.mecalife.com\/wp-content\/uploads\/2021\/09\/mecavin_google_g.svg\" class=\"attachment-full size-full wp-image-20950\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-09c6f2e\" data-id=\"09c6f2e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-058d50a elementor-widget elementor-widget-shortcode\" data-id=\"058d50a\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-shortcode\"><div id=\"google-business-reviews-rating-3\" class=\"google-business-reviews-rating gmbrr\">\r\n\t<p class=\"rating\"><span class=\"number\">4,6<\/span> <span class=\"all-stars\"><span class=\"star\"><\/span><span class=\"star\"><\/span><span class=\"star\"><\/span><span class=\"star\"><\/span><span class=\"star split-60-40\"><\/span><\/span> <\/p>\r\n<\/div>\r\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-75b85af elementor-widget elementor-widget-shortcode\" data-id=\"75b85af\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-shortcode\"><span style=\"color:#283142;\"> sur 1744 Avis Google<\/span><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-14a3ac2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"14a3ac2\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-90edc7e\" data-id=\"90edc7e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e43d3ec elementor-widget elementor-widget-heading\" data-id=\"e43d3ec\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ci hanno fatto<br>\nfiducia<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-168012c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"168012c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c53b466\" data-id=\"c53b466\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bee906d elementor-widget elementor-widget-shortcode\" data-id=\"bee906d\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-shortcode\"><div id=\"google-business-reviews-rating-5\" class=\"google-business-reviews-rating gmbrr columns one\">\r\n\t<p class=\"rating\"><\/p>\r\n<ul class=\"listing\">\r\n\t\t<li class=\"rating-5 no-date\" data-index=\"0\">\r\n\t\t\t<span class=\"author-avatar\"><a href=\"https:\/\/www.google.com\/maps\/contrib\/101382005288438121128\" target=\"_blank\" rel=\"nofollow\"><img decoding=\"async\" src=\"https:\/\/lh3.googleusercontent.com\/a\/AATXAJxiRHh7KRa1XcD_M5wbaLYZ_5VQ68nFim7R0G6A=s40-c-c0x00000000-cc-rp-mo-br100\" alt=\"Avatar\"><\/a><\/span>\r\n\t\t\t<span class=\"review-meta\">\r\n\t\t\t\t<span class=\"author-name\"><a href=\"https:\/\/www.google.com\/maps\/contrib\/101382005288438121128\" target=\"_blank\" rel=\"nofollow\">antonio D<\/a><\/span>\r\n\t\t\t\t<span class=\"rating\">\u2605\u2605\u2605\u2605\u2605<\/span>\r\n\t\t\t<\/span>\r\n\t\t\t<div class=\"text\">Rapporto pronto in 1 ora. Molto completo. Tutte le informazioni su prezzo, opzioni, modello... Davvero utile<\/div>\r\n\t\t<\/li>\r\n\t\t<li class=\"rating-5 no-date\" data-index=\"1\">\r\n\t\t\t<span class=\"author-avatar\"><a href=\"https:\/\/www.google.com\/maps\/contrib\/113759106678705533491\" target=\"_blank\" rel=\"nofollow\"><img decoding=\"async\" src=\"https:\/\/lh3.googleusercontent.com\/a\/AATXAJz2LTeshNlhs-nsDPmY64I1AzK8cnJ2BGd96zw0=s40-c-c0x00000000-cc-rp-mo-br100\" alt=\"Avatar\"><\/a><\/span>\r\n\t\t\t<span class=\"review-meta\">\r\n\t\t\t\t<span class=\"author-name\"><a href=\"https:\/\/www.google.com\/maps\/contrib\/113759106678705533491\" target=\"_blank\" rel=\"nofollow\">Pascal C<\/a><\/span>\r\n\t\t\t\t<span class=\"rating\">\u2605\u2605\u2605\u2605\u2605<\/span>\r\n\t\t\t<\/span>\r\n\t\t\t<div class=\"text\">Molto soddisfatti del servizio! Impressionante avere tutte le opzioni (e i loro prezzi originali).<\/div>\r\n\t\t<\/li>\r\n\t\t<li class=\"rating-5 no-date\" data-index=\"2\">\r\n\t\t\t<span class=\"author-avatar\"><a href=\"https:\/\/www.google.com\/maps\/contrib\/116868647719775191412\" target=\"_blank\" rel=\"nofollow\"><img decoding=\"async\" src=\"https:\/\/lh3.googleusercontent.com\/a\/AATXAJxhEpwFmg3lmH_HeF1ycHHAuQuGvRTOPD9Ha9vp=s40-c-c0x00000000-cc-rp-mo-br100\" alt=\"Avatar\"><\/a><\/span>\r\n\t\t\t<span class=\"review-meta\">\r\n\t\t\t\t<span class=\"author-name\"><a href=\"https:\/\/www.google.com\/maps\/contrib\/116868647719775191412\" target=\"_blank\" rel=\"nofollow\">Pascal H<\/a><\/span>\r\n\t\t\t\t<span class=\"rating\">\u2605\u2605\u2605\u2605\u2605<\/span>\r\n\t\t\t<\/span>\r\n\t\t\t<div class=\"text text-excerpt\"><span class=\"review-snippet\">Sito molto serio che fornisce informazioni precise e quindi molto utile per una vendita che a volte pu\u00f2 essere truccata sull'equipaggiamento e sugli optional a volte annunciati sul veicolo. Le informazioni raccolte da M\u00e9caVin permettono di realizzare<\/span> <span class=\"review-more-placeholder\">... Altro<\/span><span class=\"review-full-text\"> per fare luce sull'argomento e ripristinare cos\u00ec la verit\u00e0. Grazie per il vostro aiuto!<\/span><\/div>\r\n\t\t<\/li>\r\n\t<\/ul>\r\n<\/div>\r\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-9cb729c\" data-id=\"9cb729c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ab00331 elementor-hidden-phone elementor-widget elementor-widget-shortcode\" data-id=\"ab00331\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-shortcode\"><div id=\"google-business-reviews-rating-6\" class=\"google-business-reviews-rating gmbrr columns one\">\r\n\t<p class=\"rating\"><\/p>\r\n<ul class=\"listing\">\r\n\t\t<li class=\"rating-5 no-date\" data-index=\"0\">\r\n\t\t\t<span class=\"author-avatar\"><a href=\"https:\/\/www.google.com\/maps\/contrib\/113636936759180525067\" target=\"_blank\" rel=\"nofollow\"><img decoding=\"async\" src=\"https:\/\/lh3.googleusercontent.com\/a\/AATXAJyFh3YfgIOOdCRU0Ozlm7dPI1VzgSusyfwuRljT=s40-c-c0x00000000-cc-rp-mo-br100\" alt=\"Avatar\"><\/a><\/span>\r\n\t\t\t<span class=\"review-meta\">\r\n\t\t\t\t<span class=\"author-name\"><a href=\"https:\/\/www.google.com\/maps\/contrib\/113636936759180525067\" target=\"_blank\" rel=\"nofollow\">Pascal L<\/a><\/span>\r\n\t\t\t\t<span class=\"rating\">\u2605\u2605\u2605\u2605\u2605<\/span>\r\n\t\t\t<\/span>\r\n\t\t\t<div class=\"text\">Ho ricevuto il rapporto entro poche ore dalla richiesta, efficiente! Soprattutto per essere sicuri della finitura di un veicolo e degli optional di fabbrica.<\/div>\r\n\t\t<\/li>\r\n\t\t<li class=\"rating-4 no-date\" data-index=\"1\">\r\n\t\t\t<span class=\"author-avatar\"><a href=\"https:\/\/www.google.com\/maps\/contrib\/115821247634918826723\" target=\"_blank\" rel=\"nofollow\"><img decoding=\"async\" src=\"https:\/\/lh3.googleusercontent.com\/a\/AATXAJx-jsxOp8GA3EBoNe-OjTGk_2X8a_LkxkZrS4oi=s40-c-c0x00000000-cc-rp-mo-br100\" alt=\"Avatar\"><\/a><\/span>\r\n\t\t\t<span class=\"review-meta\">\r\n\t\t\t\t<span class=\"author-name\"><a href=\"https:\/\/www.google.com\/maps\/contrib\/115821247634918826723\" target=\"_blank\" rel=\"nofollow\">Matthieu G<\/a><\/span>\r\n\t\t\t\t<span class=\"rating\">\u2605\u2605\u2605\u2605<span class=\"not\">\u2606<\/span><\/span>\r\n\t\t\t<\/span>\r\n\t\t\t<div class=\"text\">Consiglio a chiunque acquisti o abbia acquistato un'auto usata di conoscere tutti gli optional del veicolo!<\/div>\r\n\t\t<\/li>\r\n\t\t<li class=\"rating-5 no-date\" data-index=\"2\">\r\n\t\t\t<span class=\"author-avatar\"><a href=\"https:\/\/www.google.com\/maps\/contrib\/114525264623493891869\" target=\"_blank\" rel=\"nofollow\"><img decoding=\"async\" src=\"https:\/\/lh3.googleusercontent.com\/a\/AATXAJzNSqpYrPhGwUqbZb7EXscDTMSWOZ_JUfRSJQTZ=s40-c-c0x00000000-cc-rp-mo-br100\" alt=\"Avatar\"><\/a><\/span>\r\n\t\t\t<span class=\"review-meta\">\r\n\t\t\t\t<span class=\"author-name\"><a href=\"https:\/\/www.google.com\/maps\/contrib\/114525264623493891869\" target=\"_blank\" rel=\"nofollow\">Jo\u00ebl M<\/a><\/span>\r\n\t\t\t\t<span class=\"rating\">\u2605\u2605\u2605\u2605\u2605<\/span>\r\n\t\t\t<\/span>\r\n\t\t\t<div class=\"text\">Il sito MecaVIN mi ha permesso di scoprire opzioni che il venditore non aveva presentato nel suo annuncio.<\/div>\r\n\t\t<\/li>\r\n\t<\/ul>\r\n<\/div>\r\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-6895702 elementor-widget elementor-widget-template\" data-id=\"6895702\" data-element_type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"section\" data-elementor-id=\"28212\" class=\"elementor elementor-28212\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5fadcaa elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5fadcaa\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d25f3e5\" data-id=\"d25f3e5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-eda1552 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"eda1552\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-custom\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a80d29d\" data-id=\"a80d29d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f883b17 elementor-align-right elementor-mobile-align-justify elementor-widget elementor-widget-button\" data-id=\"f883b17\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/vin.mecalife.com\/it_it\/avviso-google-mecavin\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Vedi tutte le recensioni di Google<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4a6e2e3\" data-id=\"4a6e2e3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f792788 elementor-button-align-start elementor-widget elementor-widget-form\" data-id=\"f792788\" data-element_type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;Suivant&quot;,&quot;step_previous_label&quot;:&quot;Pr\\u00e9c\\u00e9dent&quot;,&quot;step_type&quot;:&quot;none&quot;,&quot;button_width&quot;:&quot;100&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" name=\"Nouveau formulaire\" action=\"\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"28212\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"f792788\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"MecaVIN FR\" \/>\n\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-hidden elementor-field-group elementor-column elementor-field-group-idaff elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"hidden\" name=\"form_fields[idaff]\" id=\"form-field-idaff\" class=\"elementor-field elementor-size-xs  elementor-field-textual\" value=\"3\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-hidden elementor-field-group elementor-column elementor-field-group-src elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"hidden\" name=\"form_fields[src]\" id=\"form-field-src\" class=\"elementor-field elementor-size-xs  elementor-field-textual\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text\">\n\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[field_11a3bf9]\" id=\"form-field-field_11a3bf9\" class=\"elementor-field elementor-size-xs\" style=\"display:none !important;\">\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button class=\"elementor-button elementor-size-lg\" type=\"submit\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">OTTENERE IL RAPPORTO<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<input type=\"hidden\" name=\"trp-form-language\" value=\"it_it\"\/><\/form>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-80e865c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"80e865c\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fc0fdd0\" data-id=\"fc0fdd0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-81276df elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"81276df\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-e1a5c93\" data-id=\"e1a5c93\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-de15af7 elementor-widget elementor-widget-heading\" data-id=\"de15af7\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Siamo utili a tutti<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-33855a1 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"33855a1\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-9aca18e\" data-id=\"9aca18e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9ed5f06 elementor-widget__width-inherit elementor-widget elementor-widget-jet-carousel\" data-id=\"9ed5f06\" data-element_type=\"widget\" data-widget_type=\"jet-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-jet-carousel jet-elements\"><div class=\"jet-carousel-wrap\">\n\t<div class=\"jet-carousel\" data-slider_options=\"{&quot;slidesToShow&quot;:{&quot;desktop&quot;:3,&quot;tablet&quot;:2,&quot;mobile&quot;:1},&quot;autoplaySpeed&quot;:5000,&quot;autoplay&quot;:true,&quot;infinite&quot;:true,&quot;centerMode&quot;:true,&quot;pauseOnHover&quot;:false,&quot;speed&quot;:500,&quot;arrows&quot;:false,&quot;dots&quot;:false,&quot;slidesToScroll&quot;:{&quot;desktop&quot;:1,&quot;tablet&quot;:1,&quot;mobile&quot;:1},&quot;variableWidth&quot;:false,&quot;prevArrow&quot;:&quot;.jet-carousel__prev-arrow-9ed5f06&quot;,&quot;nextArrow&quot;:&quot;.jet-carousel__next-arrow-9ed5f06&quot;,&quot;rtl&quot;:false,&quot;fractionNav&quot;:false}\" dir=\"ltr\">\n\t<div class=\"elementor-slick-slider\">\n<div class=\"jet-carousel__item\">\n\t<div class=\"jet-carousel__item-inner\"><a href=\"#\" class=\"jet-carousel__item-link\" ><img decoding=\"async\" src=\"https:\/\/vin.mecalife.com\/wp-content\/uploads\/2021\/09\/mecavin_identification-voiture_acheteur.jpg\" class=\"jet-carousel__item-img\" alt=\"\" loading=\"lazy\"><\/a><div class=\"jet-carousel__content\"><h3 class=\"jet-carousel__item-title\">Acquirente<\/h3><div class=\"jet-carousel__item-text\"><h4>Acquistare una DACIA LODGY? Vi aiutiamo a fare la scelta giusta!<\/h4>\n\n<p>Il processo di acquisto di una DACIA LODGY pu\u00f2 essere stressante, MecaVIN vi aiuta a prendere la decisione giusta fornendovi un rapporto dettagliato in modo da sapere cosa state acquistando e il valore reale dell'auto.<\/p>\n\n<div class=\"su-spoiler su-spoiler-style-default su-spoiler-icon-plus-circle su-spoiler-closed\" data-scroll-offset=\"0\" data-anchor-in-url=\"no\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span>In dettaglio<\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">\n En utilisant le  num\u00e9ro d&rsquo;identification (VIN) ou l&rsquo;immatriculation du DACIA LODGY 2012\u00a02019 , les rapports de MecaVIN vous fourniront :\n<ul>\n \t<li>Il modello preciso di DACIA LODGY<\/li>\n \t<li>La finitura esatta<\/li>\n \t<li>Elenco delle opzioni del veicolo e dei relativi prezzi<\/li>\n \t<li>Elenco delle dotazioni standard<\/li>\n \t<li>Il tipo di motore e di cambio<\/li>\n \t<li>Il prezzo del nuovo veicolo<\/li>\n \t<li>Codici e denominazioni delle vernici per interni ed esterni con i relativi prezzi<\/li>\n \t<li>Dati tecnici aggiuntivi <\/li>\n<\/ul>\nGr\u00e2ce \u00e0  ces  rapports, vous pouvez  juger  si le prix  de l&rsquo;annonce  correspond bien \u00e0 la  vraie valeur du  DACIA LODGY 2012 2019,  ceci  vous prot\u00e8ge contre les annonces trompeuses ou avec  peu d&rsquo;information  . Nous vous fournissons les informations pertinentes  qui peuvent vous  aider \u00e0 n\u00e9gocier les  prix et \u00e9conomiser facilement des centaines.\n<\/div><\/div><\/div><\/div><\/div>\n<\/div>\n<div class=\"jet-carousel__item\">\n\t<div class=\"jet-carousel__item-inner\"><a href=\"#\" class=\"jet-carousel__item-link\" ><img decoding=\"async\" src=\"https:\/\/vin.mecalife.com\/wp-content\/uploads\/2021\/09\/mecavin_identification-voiture_vendeur.jpg\" class=\"jet-carousel__item-img\" alt=\"\" loading=\"lazy\"><\/a><div class=\"jet-carousel__content\"><h3 class=\"jet-carousel__item-title\">Venditore<\/h3><div class=\"jet-carousel__item-text\"><h4>Siamo qui per aiutarvi\nvendete la vostra DACIA LODGY pi\u00f9 velocemente!<\/h4>\n\n<p> Quando vendete la vostra DACIA LODGY , volete concludere la vendita in anticipo e ottenere il miglior prezzo. Fornendo ai potenziali acquirenti una relazione tecnica completa sulla vostra DACIA LODGY 2012 2019, non solo li rassicurate, ma accelerate anche il processo di vendita.<\/p>\n\n<div class=\"su-spoiler su-spoiler-style-default su-spoiler-icon-plus-circle su-spoiler-closed\" data-scroll-offset=\"0\" data-anchor-in-url=\"no\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span>In dettaglio<\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">\n Gr\u00e2ce au  num\u00e9ro  d&rsquo;identification du v\u00e9hicule (VIN)  , les rapports MecaVIN vous  indiqueront  :\n<ul>\n \t<li>Il modello preciso di DACIA LODGY<\/li>\n \t<li>La finitura esatta<\/li>\n \t<li>Elenco delle opzioni del veicolo e dei relativi prezzi<\/li>\n \t<li>Elenco delle dotazioni standard<\/li>\n \t<li>Il tipo di motore e di cambio<\/li>\n \t<li>Il prezzo del nuovo veicolo<\/li>\n \t<li>Codici e denominazioni delle vernici per interni ed esterni con i relativi prezzi<\/li>\n \t<li>Dati tecnici aggiuntivi <\/li>\n<\/ul>\n Gr\u00e2ce \u00e0   nos rapports  MecaVIN, vous  auriez  les informations techniques sur votre DACIA LODGY 2012 2019 qui vous aideront \u00e0  d\u00e9cider  un prix juste pour votre  v\u00e9hicule . Cela vous permettra de partager le rapport avec un client potentiel ou un concessionnaire  au moment  de la pr\u00e9sentation de votre DACIA LODGY .\n<\/div><\/div>\n<\/div><\/div><\/div>\n<\/div>\n<div class=\"jet-carousel__item\">\n\t<div class=\"jet-carousel__item-inner\"><a href=\"#\" class=\"jet-carousel__item-link\" ><img decoding=\"async\" src=\"https:\/\/vin.mecalife.com\/wp-content\/uploads\/2021\/09\/mecavin_identification-voiture_proprietaire.jpg\" class=\"jet-carousel__item-img\" alt=\"\" loading=\"lazy\"><\/a><div class=\"jet-carousel__content\"><h3 class=\"jet-carousel__item-title\">Proprietario<\/h3><div class=\"jet-carousel__item-text\"><h4>Volete sapere tutto sulla vostra DACIA LODGY?<\/h4>\n\n<p>Sei gi\u00e0 un orgoglioso proprietario di una DACIA LODGY , ma vuoi saperne di pi\u00f9 sull'equipaggiamento e sulle caratteristiche della tua auto?  I nostri rapporti forniscono risposte a tutte le domande sui dati tecnici della vostra DACIA LODGY , queste informazioni sono verificate dai nostri esperti di identificazione dei veicoli. In questo modo potrete verificare le informazioni che vi sono state fornite al momento dell'acquisto del vostro DACIA LODGY .<\/p>\n\n<div class=\"su-spoiler su-spoiler-style-default su-spoiler-icon-plus-circle su-spoiler-closed\" data-scroll-offset=\"0\" data-anchor-in-url=\"no\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span>In dettaglio<\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">\n Nos  rapports MecaVIN vous  donnent  toutes les informations techniques n\u00e9cessaires pour conna\u00eetre tout le potentiel de votre DACIA LODGY ainsi que sa valeur.\n\nEn utilisant votre  num\u00e9ro d&rsquo;identification (VIN) ou l&rsquo;immatriculation  de l&rsquo;automobile  , les rapports MecaVIN vous fourniront :\n<ul>\n \t<li>Il modello preciso di DACIA LODGY<\/li>\n \t<li>La finitura esatta<\/li>\n \t<li>Elenco delle opzioni del veicolo e dei relativi prezzi<\/li>\n \t<li>Elenco delle dotazioni standard<\/li>\n \t<li>Il tipo di motore e di cambio<\/li>\n \t<li>Il prezzo del nuovo veicolo<\/li>\n \t<li>Codici e denominazioni delle vernici per interni ed esterni con i relativi prezzi<\/li>\n \t<li>Dati tecnici aggiuntivi <\/li>\n<\/ul>\n<\/div><\/div>\n<\/div><\/div><\/div>\n<\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-944b106 elementor-widget elementor-widget-template\" data-id=\"944b106\" data-element_type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"section\" data-elementor-id=\"28219\" class=\"elementor elementor-28219\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9d5156d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9d5156d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b39eaad\" data-id=\"b39eaad\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b5424bb elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b5424bb\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-custom\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-663cdc1\" data-id=\"663cdc1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7dc9535 elementor-button-align-stretch elementor-widget elementor-widget-form\" data-id=\"7dc9535\" data-element_type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;Suivant&quot;,&quot;step_previous_label&quot;:&quot;Pr\\u00e9c\\u00e9dent&quot;,&quot;step_type&quot;:&quot;none&quot;,&quot;button_width&quot;:&quot;100&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" name=\"Nouveau formulaire\" action=\"\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"28219\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"7dc9535\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"MecaVIN FR\" \/>\n\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-hidden elementor-field-group elementor-column elementor-field-group-idaff elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"hidden\" name=\"form_fields[idaff]\" id=\"form-field-idaff\" class=\"elementor-field elementor-size-xs  elementor-field-textual\" value=\"3\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-hidden elementor-field-group elementor-column elementor-field-group-src elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"hidden\" name=\"form_fields[src]\" id=\"form-field-src\" class=\"elementor-field elementor-size-xs  elementor-field-textual\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text\">\n\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[field_11a3bf9]\" id=\"form-field-field_11a3bf9\" class=\"elementor-field elementor-size-xs\" style=\"display:none !important;\">\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button class=\"elementor-button elementor-size-lg\" type=\"submit\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">OTTENERE IL RAPPORTO<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<input type=\"hidden\" name=\"trp-form-language\" value=\"it_it\"\/><\/form>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-939de51 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"939de51\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ec0840d\" data-id=\"ec0840d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4f7ea46 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4f7ea46\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-cf6610d\" data-id=\"cf6610d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cb7c0c9 elementor-widget elementor-widget-heading\" data-id=\"cb7c0c9\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">FAQ<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3d2a5e7 elementor-widget elementor-widget-heading\" data-id=\"3d2a5e7\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Trova finiture e attrezzature\n<span style=\"color:#19D180;\"> DACIA LODGY<\/span><\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e609ea2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e609ea2\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-23c899f\" data-id=\"23c899f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-11b5cfa elementor-widget elementor-widget-toggle\" data-id=\"11b5cfa\" data-element_type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.22.0 - 26-06-2024 *\/\n.elementor-toggle{text-align:start}.elementor-toggle .elementor-tab-title{font-weight:700;line-height:1;margin:0;padding:15px;border-bottom:1px solid #d5d8dc;cursor:pointer;outline:none}.elementor-toggle .elementor-tab-title .elementor-toggle-icon{display:inline-block;width:1em}.elementor-toggle .elementor-tab-title .elementor-toggle-icon svg{margin-inline-start:-5px;width:1em;height:1em}.elementor-toggle .elementor-tab-title .elementor-toggle-icon.elementor-toggle-icon-right{float:right;text-align:right}.elementor-toggle .elementor-tab-title .elementor-toggle-icon.elementor-toggle-icon-left{float:left;text-align:left}.elementor-toggle .elementor-tab-title .elementor-toggle-icon .elementor-toggle-icon-closed{display:block}.elementor-toggle .elementor-tab-title .elementor-toggle-icon .elementor-toggle-icon-opened{display:none}.elementor-toggle .elementor-tab-title.elementor-active{border-bottom:none}.elementor-toggle .elementor-tab-title.elementor-active .elementor-toggle-icon-closed{display:none}.elementor-toggle .elementor-tab-title.elementor-active .elementor-toggle-icon-opened{display:block}.elementor-toggle .elementor-tab-content{padding:15px;border-bottom:1px solid #d5d8dc;display:none}@media (max-width:767px){.elementor-toggle .elementor-tab-title{padding:12px}.elementor-toggle .elementor-tab-content{padding:12px 10px}}.e-con-inner>.elementor-widget-toggle,.e-con>.elementor-widget-toggle{width:var(--container-widget-width);--flex-grow:var(--container-widget-flex-grow)}<\/style>\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h4 id=\"elementor-tab-title-1851\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1851\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8zm144 276c0 6.6-5.4 12-12 12h-92v92c0 6.6-5.4 12-12 12h-56c-6.6 0-12-5.4-12-12v-92h-92c-6.6 0-12-5.4-12-12v-56c0-6.6 5.4-12 12-12h92v-92c0-6.6 5.4-12 12-12h56c6.6 0 12 5.4 12 12v92h92c6.6 0 12 5.4 12 12v56z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-minus-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8zM124 296c-6.6 0-12-5.4-12-12v-56c0-6.6 5.4-12 12-12h264c6.6 0 12 5.4 12 12v56c0 6.6-5.4 12-12 12H124z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Come trovare il numero di serie \/ codice vino di DACIA LODGY?<\/a>\n\t\t\t\t\t<\/h4>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1851\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1851\"><p>Utilizziamo un sistema automatizzato che ci permette di determinare il numero di serie del veicolo dalla targa della vostra DACIA LODGY.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h4 id=\"elementor-tab-title-1852\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-1852\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8zm144 276c0 6.6-5.4 12-12 12h-92v92c0 6.6-5.4 12-12 12h-56c-6.6 0-12-5.4-12-12v-92h-92c-6.6 0-12-5.4-12-12v-56c0-6.6 5.4-12 12-12h92v-92c0-6.6 5.4-12 12-12h56c6.6 0 12 5.4 12 12v92h92c6.6 0 12 5.4 12 12v56z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-minus-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8zM124 296c-6.6 0-12-5.4-12-12v-56c0-6.6 5.4-12 12-12h264c6.6 0 12 5.4 12 12v56c0 6.6-5.4 12-12 12H124z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Elenco delle opzioni con numero di serie\/codice vino<\/a>\n\t\t\t\t\t<\/h4>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1852\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-1852\"><p>Vi forniamo un elenco completo degli optional e delle dotazioni originali del veicolo che desiderate acquistare.<\/p><p>Dopo aver compilato il modulo di domanda, riceverete un'e-mail con tutte le informazioni necessarie.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h4 id=\"elementor-tab-title-1853\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-1853\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8zm144 276c0 6.6-5.4 12-12 12h-92v92c0 6.6-5.4 12-12 12h-56c-6.6 0-12-5.4-12-12v-92h-92c-6.6 0-12-5.4-12-12v-56c0-6.6 5.4-12 12-12h92v-92c0-6.6 5.4-12 12-12h56c6.6 0 12 5.4 12 12v92h92c6.6 0 12 5.4 12 12v56z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-minus-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8zM124 296c-6.6 0-12-5.4-12-12v-56c0-6.6 5.4-12 12-12h264c6.6 0 12 5.4 12 12v56c0 6.6-5.4 12-12 12H124z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Individuare le caratteristiche del veicolo con la targa.<\/a>\n\t\t\t\t\t<\/h4>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1853\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-1853\"><p>Quando si cerca una DACIA LODGY usata su siti come\u00a0<a href=\"https:\/\/www.leboncoin.fr\/voitures\/offres\/\">leboncoin<\/a>\u00a0,\u00a0<a href=\"https:\/\/www.lacentrale.fr\/\">l'impianto<\/a>e tutti gli altri siti di vendita di auto usate. Si pu\u00f2 praticamente indovinare la pubblicit\u00e0 su cui sono indicati il modello, la finitura e le varie caratteristiche. Purtroppo, gli annunci dei privati contengono spesso poche informazioni, per cui \u00e8 pi\u00f9 sicuro per voi acquisire le caratteristiche corrette del veicolo attraverso una terza parte.<\/p><p>Ecco perch\u00e9\u00a0<a href=\"https:\/\/vin.mecalife.com\/it_it\/\">MecaVIN\u00a0<\/a>fornisce un rapporto che identifica il modello, la finitura e le varie caratteristiche, come le dotazioni opzionali e di serie. Vi forniamo dati affidabili e originali.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h4 id=\"elementor-tab-title-1854\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-1854\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8zm144 276c0 6.6-5.4 12-12 12h-92v92c0 6.6-5.4 12-12 12h-56c-6.6 0-12-5.4-12-12v-92h-92c-6.6 0-12-5.4-12-12v-56c0-6.6 5.4-12 12-12h92v-92c0-6.6 5.4-12 12-12h56c6.6 0 12 5.4 12 12v92h92c6.6 0 12 5.4 12 12v56z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-minus-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8zM124 296c-6.6 0-12-5.4-12-12v-56c0-6.6 5.4-12 12-12h264c6.6 0 12 5.4 12 12v56c0 6.6-5.4 12-12 12H124z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Per aiutarvi nella decisione di acquistare una DACIA LODGY vi permettiamo di .<\/a>\n\t\t\t\t\t<\/h4>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1854\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-1854\"><ul><li>Valutare la corrispondenza dei prezzi dell'annuncio DACIA LODGY<\/li><li>Negoziare al meglio il prezzo di acquisto finale<\/li><li>Risparmiate facilmente diverse centinaia di euro<\/li><li>Protezione dagli annunci incompleti<\/li><\/ul><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h4 id=\"elementor-tab-title-1855\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"button\" aria-controls=\"elementor-tab-content-1855\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8zm144 276c0 6.6-5.4 12-12 12h-92v92c0 6.6-5.4 12-12 12h-56c-6.6 0-12-5.4-12-12v-92h-92c-6.6 0-12-5.4-12-12v-56c0-6.6 5.4-12 12-12h92v-92c0-6.6 5.4-12 12-12h56c6.6 0 12 5.4 12 12v92h92c6.6 0 12 5.4 12 12v56z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-minus-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8zM124 296c-6.6 0-12-5.4-12-12v-56c0-6.6 5.4-12 12-12h264c6.6 0 12 5.4 12 12v56c0 6.6-5.4 12-12 12H124z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Vi forniamo le seguenti informazioni via e-mail.<\/a>\n\t\t\t\t\t<\/h4>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1855\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"region\" aria-labelledby=\"elementor-tab-title-1855\"><ul><li>Marca e modello con finitura esatta<\/li><li>Elenco preciso degli equipaggiamenti scelti al momento dell'acquisto di una nuova DACIA LODGY<\/li><li>Preventivo preciso per DACIA LODGY in base al modello, alla finitura e all'anno.<\/li><\/ul><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<script type=\"application\/ld+json\">{\n    \"@context\": \"https:\\\/\\\/schema.org\",\n    \"@type\": \"FAQPage\",\n    \"mainEntity\": [\n        {\n            \"@type\": \"Question\",\n            \"name\": \"Comment trouver le n\\u00b0 de s\\u00e9rie \\\/ code vin DACIA LODGY ?\",\n            \"acceptedAnswer\": {\n                \"@type\": \"Answer\",\n                \"text\": \"<p>Nous utilisons un syst\\u00e8me automatis\\u00e9e qui nous permets de conna\\u00eetre le num\\u00e9ro de s\\u00e9rie du v\\u00e9hicule \\u00e0 partir de la plaque d\\u2019immatriculation de votre DACIA LODGY.<\\\/p>\"\n            }\n        },\n        {\n            \"@type\": \"Question\",\n            \"name\": \"Liste d\\u2019options avec num\\u00e9ro de s\\u00e9rie \\\/ code vin\",\n            \"acceptedAnswer\": {\n                \"@type\": \"Answer\",\n                \"text\": \"<p>Nous vous fournissons la liste compl\\u00e8te des options et \\u00e9quipements d\\u2019origine du v\\u00e9hicule que vous d\\u00e9sirez achet\\u00e9.<\\\/p><p>Vous recevrez par email les diff\\u00e9rentes indications apr\\u00e8s avoir remplis le formulaire de demande.<\\\/p>\"\n            }\n        },\n        {\n            \"@type\": \"Question\",\n            \"name\": \"Trouver les caract\\u00e9ristiques du v\\u00e9hicule avec la plaque immatriculation.\\u200b\",\n            \"acceptedAnswer\": {\n                \"@type\": \"Answer\",\n                \"text\": \"<p>Lorsque vous cherchez une DACIA LODGY d&rsquo;occasion sur les sites tels que\\u00a0<a href=\\\"https:\\\/\\\/www.leboncoin.fr\\\/voitures\\\/offres\\\/\\\">leboncoin<\\\/a>\\u00a0,\\u00a0<a href=\\\"https:\\\/\\\/www.lacentrale.fr\\\/\\\">la centrale<\\\/a>, ainsi que tous les autres sites de ventes de v\\u00e9hicules d&rsquo;occasion. Vous devinez virtuellement l&rsquo;annonce sur laquelle est indiqu\\u00e9 le mod\\u00e8le, la finition et les diff\\u00e9rents caract\\u00e9ristiques. Malheureusement les annonces de particulier comporte tr\\u00e8s souvent peu d&rsquo;indications de ce fait il est s\\u00e9curisant pour vous d&rsquo;acqu\\u00e9rir via une tierce partie les caract\\u00e9ristiques ad\\u00e9quates du v\\u00e9hicule.<\\\/p><p>Voil\\u00e0 pourquoi\\u00a0<a href=\\\"https:\\\/\\\/vin.mecalife.com\\\/\\\">MecaVIN\\u00a0<\\\/a>vous fourni un compte rendu d&rsquo;identification du mod\\u00e8le, de la finition ainsi que les diff\\u00e9rentes caract\\u00e9ristiques tels que les \\u00e9quipements en options et de s\\u00e9rie. Nous vous fournissons des donn\\u00e9es fiables et d&rsquo;origine.<\\\/p>\"\n            }\n        },\n        {\n            \"@type\": \"Question\",\n            \"name\": \"Pour vous aider au mieux dans votre  d\\u00e9cision  d\\u2019achat DACIA LODGY nous vous Permettons de :\\u200b\",\n            \"acceptedAnswer\": {\n                \"@type\": \"Answer\",\n                \"text\": \"<ul><li>\\u00c9valuer la  correspondance  du prix de l\\u2019annonce DACIA LODGY<\\\/li><li>N\\u00e9gocier au mieux le prix d\\u2019achat final<\\\/li><li>\\u00c9conomiser facilement plusieurs centaines d\\u2019euros<\\\/li><li>Vous prot\\u00e9ger contre des annonces  Incompl\\u00e8tes  \\u200b<\\\/li><\\\/ul>\"\n            }\n        },\n        {\n            \"@type\": \"Question\",\n            \"name\": \"Nous vous fournissons par email les  renseignements suivants  :\\u200b\",\n            \"acceptedAnswer\": {\n                \"@type\": \"Answer\",\n                \"text\": \"<ul><li>Marque et mod\\u00e8le avec la finition exacte\\u200b<\\\/li><li>Liste pr\\u00e9cise d&rsquo;\\u00e9quipements choisies lors de l\\u2019achat neuf  du v\\u00e9hicule  DACIA LODGY\\u200b<\\\/li><li>C\\u00f4te pr\\u00e9cise de DACIA LODGY suivant le mod\\u00e8le, finition et ann\\u00e9e.\\u200b<\\\/li><\\\/ul>\"\n            }\n        }\n    ]\n}<\/script>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4af870f\" data-id=\"4af870f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1180869 elementor-widget elementor-widget-toggle\" data-id=\"1180869\" data-element_type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h4 id=\"elementor-tab-title-1831\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1831\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8zm144 276c0 6.6-5.4 12-12 12h-92v92c0 6.6-5.4 12-12 12h-56c-6.6 0-12-5.4-12-12v-92h-92c-6.6 0-12-5.4-12-12v-56c0-6.6 5.4-12 12-12h92v-92c0-6.6 5.4-12 12-12h56c6.6 0 12 5.4 12 12v92h92c6.6 0 12 5.4 12 12v56z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-minus-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8zM124 296c-6.6 0-12-5.4-12-12v-56c0-6.6 5.4-12 12-12h264c6.6 0 12 5.4 12 12v56c0 6.6-5.4 12-12 12H124z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Vi forniamo i dati del produttore originale<\/a>\n\t\t\t\t\t<\/h4>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1831\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1831\"><ul><li>Vi forniamo i dati originali del produttore per verificare se l'auto che desiderate acquistare corrisponde alle vostre aspettative o all'annuncio del venditore.<\/li><li>Vi offriamo un servizio su misura e la garanzia che le nostre indicazioni sono di alta qualit\u00e0.<\/li><li>Il team di MecaVIN \u00e8 disponibile via e-mail per rispondere a tutte le vostre domande.<\/li><li>Garanzia di utilit\u00e0 delle informazioni\u00a0<\/li><li>Riceverete via e-mail un elenco di tutti gli optional e gli equipaggiamenti originali.<\/li><\/ul><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h4 id=\"elementor-tab-title-1832\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-1832\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8zm144 276c0 6.6-5.4 12-12 12h-92v92c0 6.6-5.4 12-12 12h-56c-6.6 0-12-5.4-12-12v-92h-92c-6.6 0-12-5.4-12-12v-56c0-6.6 5.4-12 12-12h92v-92c0-6.6 5.4-12 12-12h56c6.6 0 12 5.4 12 12v92h92c6.6 0 12 5.4 12 12v56z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-minus-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8zM124 296c-6.6 0-12-5.4-12-12v-56c0-6.6 5.4-12 12-12h264c6.6 0 12 5.4 12 12v56c0 6.6-5.4 12-12 12H124z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Come posso trovare le caratteristiche dell'auto dalla targa?<\/a>\n\t\t\t\t\t<\/h4>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1832\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-1832\"><p>MecaVIN ha accesso alle informazioni ufficiali del produttore, nel rapporto di identificazione vi forniamo molte informazioni rilevanti in modo che possiate essere tranquilli al momento dell'acquisto.<\/p><p>Per ottenere il rapporto di identificazione \u00e8 necessario inserire i dati di immatricolazione dell'auto. Il nostro sistema di automazione riconosce immediatamente l'auto. Quindi dal numero VIN possiamo identificare con precisione il modello, la finitura, l'equipaggiamento standard e quello opzionale.<\/p><p>Riceverete il rapporto di identificazione via e-mail.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h4 id=\"elementor-tab-title-1833\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-1833\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8zm144 276c0 6.6-5.4 12-12 12h-92v92c0 6.6-5.4 12-12 12h-56c-6.6 0-12-5.4-12-12v-92h-92c-6.6 0-12-5.4-12-12v-56c0-6.6 5.4-12 12-12h92v-92c0-6.6 5.4-12 12-12h56c6.6 0 12 5.4 12 12v92h92c6.6 0 12 5.4 12 12v56z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-minus-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8zM124 296c-6.6 0-12-5.4-12-12v-56c0-6.6 5.4-12 12-12h264c6.6 0 12 5.4 12 12v56c0 6.6-5.4 12-12 12H124z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Quali informazioni sono disponibili nel rapporto di identificazione MecaVIN?<\/a>\n\t\t\t\t\t<\/h4>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1833\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-1833\"><ul><li>Il modello e il motore esatto del veicolo<\/li><li>L'esatta finitura dell'auto<\/li><li>l'elenco delle dotazioni di serie<\/li><li>l'elenco delle dotazioni opzionali<\/li><li>listino prezzi degli equipaggiamenti opzionali<\/li><li>la costa e il prezzo di mercato<\/li><li>il vino e il numero di serie<\/li><\/ul><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h4 id=\"elementor-tab-title-1834\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-1834\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8zm144 276c0 6.6-5.4 12-12 12h-92v92c0 6.6-5.4 12-12 12h-56c-6.6 0-12-5.4-12-12v-92h-92c-6.6 0-12-5.4-12-12v-56c0-6.6 5.4-12 12-12h92v-92c0-6.6 5.4-12 12-12h56c6.6 0 12 5.4 12 12v92h92c6.6 0 12 5.4 12 12v56z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-minus-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8zM124 296c-6.6 0-12-5.4-12-12v-56c0-6.6 5.4-12 12-12h264c6.6 0 12 5.4 12 12v56c0 6.6-5.4 12-12 12H124z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Come posso scoprire il modello del mio veicolo con una targa?<\/a>\n\t\t\t\t\t<\/h4>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1834\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-1834\"><p>Utilizziamo un sistema automatizzato che ci permette di determinare il numero di serie del veicolo dalla targa della vostra DACIA LODGY.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h4 id=\"elementor-tab-title-1835\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"button\" aria-controls=\"elementor-tab-content-1835\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8zm144 276c0 6.6-5.4 12-12 12h-92v92c0 6.6-5.4 12-12 12h-56c-6.6 0-12-5.4-12-12v-92h-92c-6.6 0-12-5.4-12-12v-56c0-6.6 5.4-12 12-12h92v-92c0-6.6 5.4-12 12-12h56c6.6 0 12 5.4 12 12v92h92c6.6 0 12 5.4 12 12v56z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-minus-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8zM124 296c-6.6 0-12-5.4-12-12v-56c0-6.6 5.4-12 12-12h264c6.6 0 12 5.4 12 12v56c0 6.6-5.4 12-12 12H124z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Qual \u00e8 il numero di serie o VIN?<\/a>\n\t\t\t\t\t<\/h4>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1835\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"region\" aria-labelledby=\"elementor-tab-title-1835\"><p>Il numero\u00a0<a href=\"https:\/\/fr.wikipedia.org\/wiki\/Vehicle_Identification_Number\">VIN (numero di identificazione del veicolo)<\/a>\u00a0\u00e8 il numero di serie dell'auto. Si trova nella riga E della carta di circolazione.<\/p><p>\u00c8 simile al numero inciso sul telaio dell'auto. Ogni produttore deve assegnare un numero di identificazione dell'auto (codice VIN) a ogni vettura prodotta. Il codice VIN \u00e8 noto anche come codice NSV (Vehicle Serial Number). Il codice VIN \u00e8 composto da una serie di 17 caratteri.\u00a0<\/p><p>Esempio VOLVO V60 2.0 D4 190hp - 2016 - YV1FWA88DH1348375 \u00a0<\/p><p>Il codice VIN \u00e8 formato dal codice produttore WMI, che \u00e8 costituito dai primi tre caratteri. Poi il codice VDS, composto da 8 caratteri, di cui gli ultimi 6 corrispondono a un numero interno del produttore.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<script type=\"application\/ld+json\">{\n    \"@context\": \"https:\\\/\\\/schema.org\",\n    \"@type\": \"FAQPage\",\n    \"mainEntity\": [\n        {\n            \"@type\": \"Question\",\n            \"name\": \"Nous vous fournissons les d\\u00e9tails d\\u2019origine constructeur\",\n            \"acceptedAnswer\": {\n                \"@type\": \"Answer\",\n                \"text\": \"<ul><li>Nous vous fournissons les donn\\u00e9es d\\u2019origine constructeur afin de v\\u00e9rifier si  la voiture  que vous souhaitez acheter correspond bien \\u00e0 vos attentes ou \\u00e0 l\\u2019annonce du vendeur.<\\\/li><li>Nous vous fournissons un service sur mesure et une garantie  que nos indications sont de qualit\\u00e9.<\\\/li><li>L\\u2019\\u00e9quipe\\u00a0MecaVIN\\u00a0est\\u00a0disponible\\u00a0par email pour\\u00a0r\\u00e9pondre\\u00a0\\u00e0 toutes vos\\u00a0questions compl\\u00e9mentaires.<\\\/li><li>Garantie d&rsquo;utilit\\u00e9  des renseignements\\u00a0<\\\/li><li>Vous recevrez par email la liste de l\\u2019ensemble des options d\\u2019origine ainsi que les \\u00e9quipements d\\u2019origine.<\\\/li><\\\/ul>\"\n            }\n        },\n        {\n            \"@type\": \"Question\",\n            \"name\": \"Comment retrouver les caract\\u00e9ristiques de la voiture \\u00e0 partir de la plaque d\\u2019immatriculation ?\\u200b\",\n            \"acceptedAnswer\": {\n                \"@type\": \"Answer\",\n                \"text\": \"<p>MecaVIN \\u00e0 acc\\u00e8s aux informations officielles des fabricants, dans le rapport d&rsquo;identification nous vous fournissons de nombreuses informations pertinentes afin que vous puissiez \\u00eatre \\u00e0 l&rsquo;aise lors de votre achat .<\\\/p><p>Pour obtenir le rapport d&rsquo;identification vous devez entrer les renseignements relatives \\u00e0 l&rsquo;immatriculation de la voiture \\u200b notre syst\\u00e8me d&rsquo;automatisation reconna\\u00eet imm\\u00e9diatement la voiture . Ensuite \\u00e0 partir du num\\u00e9ro VIN nous pouvons pr\\u00e9cis\\u00e9ment identifier le mod\\u00e8le, la finition, les \\u00e9quipements de s\\u00e9rie et les \\u00e9quipements en options.<\\\/p><p>Vous recevrez par email le rapport d&rsquo;identification.<\\\/p>\"\n            }\n        },\n        {\n            \"@type\": \"Question\",\n            \"name\": \"Quelles sont les informations  disponibles dans le compte rendu d'identification MecaVIN ?\\u200b\",\n            \"acceptedAnswer\": {\n                \"@type\": \"Answer\",\n                \"text\": \"<ul><li>Le mod\\u00e8le et la motorisation pr\\u00e9cise du v\\u00e9hicule<\\\/li><li>La finition exacte de la voiture<\\\/li><li>la liste des \\u00e9quipements de s\\u00e9rie<\\\/li><li>la liste des \\u00e9quipements en options<\\\/li><li>la liste du prix des \\u00e9quipements en options<\\\/li><li>la c\\u00f4te et le prix de march\\u00e9<\\\/li><li>le vin et le num\\u00e9ro de s\\u00e9rie<\\\/li><\\\/ul>\"\n            }\n        },\n        {\n            \"@type\": \"Question\",\n            \"name\": \"Comment connaitre mod\\u00e8le de  mon v\\u00e9hicule  avec plaque immatriculation ?\\u200b\",\n            \"acceptedAnswer\": {\n                \"@type\": \"Answer\",\n                \"text\": \"<p>Nous utilisons un syst\\u00e8me automatis\\u00e9e qui nous permets de conna\\u00eetre le num\\u00e9ro de s\\u00e9rie du v\\u00e9hicule \\u00e0 partir de la plaque d\\u2019immatriculation de votre DACIA LODGY.<\\\/p>\"\n            }\n        },\n        {\n            \"@type\": \"Question\",\n            \"name\": \"Qu'est ce que le Num\\u00e9ro VIN ou Num\\u00e9ro de s\\u00e9rie ?\\u200b\",\n            \"acceptedAnswer\": {\n                \"@type\": \"Answer\",\n                \"text\": \"<p>Le num\\u00e9ro\\u00a0<a href=\\\"https:\\\/\\\/fr.wikipedia.org\\\/wiki\\\/Vehicle_Identification_Number\\\">VIN (v\\u00e9hicle identification number)<\\\/a>\\u00a0correspond au num\\u00e9ro de s\\u00e9rie de l\\u2019automobile. Il est disponible \\u00e0 la ligne E sur le certificat d&rsquo;immatriculation.<\\\/p><p>Il est similaire au  num\\u00e9ro grav\\u00e9 sur le ch\\u00e2ssis de la voiture. Chaque constructeur doit attribuer un num\\u00e9ro d\\u2019identification de la voiture (code VIN) \\u00e0 chaque automobile qu\\u2019il produit. Le code VIN est aussi appel\\u00e9 code NSV (Num\\u00e9ro de S\\u00e9rie du V\\u00e9hicule) . Le code VIN est compos\\u00e9 d\\u2019une s\\u00e9rie de 17 caract\\u00e8res.\\u00a0<\\\/p><p>Exemple  VOLVO V60 2.0 D4 190cv &#8211; 2016 &#8211; YV1FWA88DH1348375 \\u00a0<\\\/p><p>Le code VIN est form\\u00e9 \\u00e0 partir du code Constructeur WMI, ce qui \\u00e9quivaut au trois premiers caract\\u00e8res. Ensuite le code VDS qui se compose 8 caract\\u00e8res et les 6 derniers correspondent \\u00e0 un num\\u00e9ro constructeur interne.<\\\/p>\"\n            }\n        }\n    ]\n}<\/script>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-998913c elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"998913c\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-dac4a8b\" data-id=\"dac4a8b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-bc261ff elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bc261ff\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-cdfe015\" data-id=\"cdfe015\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-805dbbe elementor-grid-5 elementor-posts--align-left elementor-posts--thumbnail-top elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-widget elementor-widget-posts\" data-id=\"805dbbe\" data-element_type=\"widget\" data-settings=\"{&quot;custom_columns&quot;:&quot;5&quot;,&quot;custom_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:6,&quot;sizes&quot;:[]},&quot;custom_columns_tablet&quot;:&quot;2&quot;,&quot;custom_columns_mobile&quot;:&quot;1&quot;,&quot;custom_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;custom_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"posts.custom\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/vin.mecalife.com\/wp-content\/plugins\/elementor-pro\/assets\/css\/widget-posts.min.css\">      <div class=\"ecs-posts elementor-posts-container elementor-posts   elementor-grid elementor-posts--skin-custom\" data-settings=\"{&quot;current_page&quot;:1,&quot;max_num_pages&quot;:0,&quot;load_method&quot;:&quot;&quot;,&quot;widget_id&quot;:&quot;805dbbe&quot;,&quot;post_id&quot;:29021,&quot;theme_id&quot;:29021,&quot;change_url&quot;:false,&quot;reinit_js&quot;:false}\">\n      <div class=\"elementor-posts-nothing-found\"><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-278762d elementor-widget elementor-widget-shortcode\" data-id=\"278762d\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-shortcode\">\n<script type=\"application\/ld+json\">{\n    \"@context\": \"https:\\\/\\\/schema.org\",\n    \"@type\": \"FAQPage\",\n    \"mainEntity\": [\n        {\n            \"@type\": \"Question\",\n            \"name\": \"Comment connaitre la finition de ma voiture ?\",\n            \"acceptedAnswer\": {\n                \"@type\": \"Answer\",\n                \"text\": \"MecaVIN vous fournit un rapport d'identification pr\\u00e9cis vous permettant de connaitre la marque, mod\\u00e8le, motorisation et finition exacte de votre v\\u00e9hicule ainsi que la liste des \\u00e9quipements de s\\u00e9rie + ceux en options.\",\n                \"image\": {\n                    \"@type\": \"ImageObject\",\n                    \"contentUrl\": \"https:\\\/\\\/vin.mecalife.com\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/mecavin-v6-lolo-png-compress.png\"\n                }\n            }\n        },\n        {\n            \"@type\": \"Question\",\n            \"name\": \"Comment Trouver la finition de ma voiture ?\",\n            \"acceptedAnswer\": {\n                \"@type\": \"Answer\",\n                \"text\": \"MecaVIN vous fournit un rapport d'identification pr\\u00e9cis vous permettant de connaitre la marque, mod\\u00e8le, motorisation et finition exacte de votre v\\u00e9hicule ainsi que la liste des \\u00e9quipements de s\\u00e9rie + ceux en options.\",\n                \"image\": {\n                    \"@type\": \"ImageObject\",\n                    \"contentUrl\": \"https:\\\/\\\/vin.mecalife.com\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/mecavin-v6-lolo-png-compress.png\"\n                }\n            }\n        },\n        {\n            \"@type\": \"Question\",\n            \"name\": \"Comment trouver finition voiture avec immatriculation ?\",\n            \"acceptedAnswer\": {\n                \"@type\": \"Answer\",\n                \"text\": \"MecaVIN vous fournit un rapport d'identification pr\\u00e9cis \\u00e0 partir de l'immatriculation de votre v\\u00e9hicule. Vous permettant de connaitre la marque, mod\\u00e8le, motorisation et finition exacte de votre voiture ainsi que la liste des \\u00e9quipements de s\\u00e9rie + ceux en options.\",\n                \"image\": {\n                    \"@type\": \"ImageObject\",\n                    \"contentUrl\": \"https:\\\/\\\/vin.mecalife.com\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/mecavin-v6-lolo-png-compress.png\"\n                }\n            }\n        }\n    ]\n}<\/script>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-265de3c elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"265de3c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2789458\" data-id=\"2789458\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e84e99d elementor-widget elementor-widget-shortcode\" data-id=\"e84e99d\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-shortcode\">\t\t<div data-elementor-type=\"footer\" data-elementor-id=\"20911\" class=\"elementor elementor-20911\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cc6d5ea elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cc6d5ea\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9731170\" data-id=\"9731170\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-40d5ec3 elementor-widget elementor-widget-heading\" data-id=\"40d5ec3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Le nostre apparizioni sui media<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2946293 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2946293\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-2ee5805\" data-id=\"2ee5805\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-07122a0 elementor-widget elementor-widget-image\" data-id=\"07122a0\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.youtube.com\/watch?v=zeEIBPPM4Xs&#038;t=108s\" target=\"_blank\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"470\" src=\"https:\/\/vin.mecalife.com\/wp-content\/uploads\/2021\/10\/lva-mecavin-porsche.jpeg\" class=\"attachment-large size-large wp-image-30378\" alt=\"\" srcset=\"https:\/\/vin.mecalife.com\/wp-content\/uploads\/2021\/10\/lva-mecavin-porsche.jpeg 800w, https:\/\/vin.mecalife.com\/wp-content\/uploads\/2021\/10\/lva-mecavin-porsche-300x176.jpeg 300w, https:\/\/vin.mecalife.com\/wp-content\/uploads\/2021\/10\/lva-mecavin-porsche-768x451.jpeg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-2ea0880\" data-id=\"2ea0880\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6ac1268 elementor-widget elementor-widget-image\" data-id=\"6ac1268\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/youtu.be\/bBn4IXLD3SM?si=-DLAdvIdETv2DMuS&#038;t=139\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"640\" height=\"360\" src=\"https:\/\/vin.mecalife.com\/wp-content\/uploads\/2024\/07\/sddefault-1.jpg\" class=\"attachment-large size-large wp-image-31573\" alt=\"\" srcset=\"https:\/\/vin.mecalife.com\/wp-content\/uploads\/2024\/07\/sddefault-1.jpg 640w, https:\/\/vin.mecalife.com\/wp-content\/uploads\/2024\/07\/sddefault-1-300x169.jpg 300w, https:\/\/vin.mecalife.com\/wp-content\/uploads\/2024\/07\/sddefault-1-18x10.jpg 18w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-416aa60\" data-id=\"416aa60\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ba6d692 elementor-widget elementor-widget-image\" data-id=\"ba6d692\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/pdlv.fr\/2020\/06\/21\/une-voiture-toutes-options-ca-existe-vraiment\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"774\" height=\"465\" src=\"https:\/\/vin.mecalife.com\/wp-content\/uploads\/2021\/09\/Capture-de\u0301cran-2022-01-27-a\u0300-10.55.20.jpg\" class=\"attachment-large size-large wp-image-30393\" alt=\"\" srcset=\"https:\/\/vin.mecalife.com\/wp-content\/uploads\/2021\/09\/Capture-de\u0301cran-2022-01-27-a\u0300-10.55.20.jpg 774w, https:\/\/vin.mecalife.com\/wp-content\/uploads\/2021\/09\/Capture-de\u0301cran-2022-01-27-a\u0300-10.55.20-300x180.jpg 300w, https:\/\/vin.mecalife.com\/wp-content\/uploads\/2021\/09\/Capture-de\u0301cran-2022-01-27-a\u0300-10.55.20-768x461.jpg 768w\" sizes=\"(max-width: 774px) 100vw, 774px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-38bca59 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"38bca59\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ca0a922\" data-id=\"ca0a922\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ef997e1 elementor-widget elementor-widget-heading\" data-id=\"ef997e1\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ci sostengono finanziariamente<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f3fa2de elementor-widget elementor-widget-image-carousel\" data-id=\"f3fa2de\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;5&quot;,&quot;slides_to_show_tablet&quot;:&quot;3&quot;,&quot;slides_to_show_mobile&quot;:&quot;2&quot;,&quot;navigation&quot;:&quot;none&quot;,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.22.0 - 26-06-2024 *\/\n.elementor-widget-image-carousel .swiper,.elementor-widget-image-carousel .swiper-container{position:static}.elementor-widget-image-carousel .swiper-container .swiper-slide figure,.elementor-widget-image-carousel .swiper .swiper-slide figure{line-height:inherit}.elementor-widget-image-carousel .swiper-slide{text-align:center}.elementor-image-carousel-wrapper:not(.swiper-container-initialized):not(.swiper-initialized) .swiper-slide{max-width:calc(100% \/ var(--e-image-carousel-slides-to-show, 3))}<\/style>\t\t<div class=\"elementor-image-carousel-wrapper swiper\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 di 5\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/vin.mecalife.com\/wp-content\/uploads\/2021\/09\/logo_adocc-lk-1.png\" alt=\"logo_adocc-lk\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 di 5\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/vin.mecalife.com\/wp-content\/uploads\/2021\/09\/logo_bpi-france-1.png\" alt=\"logo_bpi-francia\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 di 5\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/vin.mecalife.com\/wp-content\/uploads\/2021\/09\/logo_crealia-occitanie-1-300x221.png\" alt=\"logo_crealia-occitania\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 di 5\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/vin.mecalife.com\/wp-content\/uploads\/2021\/09\/logo_banque-populaire_innovation-1.png\" alt=\"logo_popolare_innovazione bancaria\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 di 5\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/vin.mecalife.com\/wp-content\/uploads\/2021\/09\/logo_la-french-tech-toulouse-1.png\" alt=\"logo_la-french-tech-toulouse\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bd8467a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bd8467a\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-42e08a0\" data-id=\"42e08a0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2a70547 elementor-mobile-align-center elementor-align-left elementor-widget elementor-widget-button\" data-id=\"2a70547\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/mecalife.com\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">MecaLIFE Group<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-393104a elementor-mobile-align-center elementor-align-left elementor-widget elementor-widget-button\" data-id=\"393104a\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/score.mecalife.com\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">MecaSCORE<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ceaae66 elementor-widget elementor-widget-shortcode\" data-id=\"ceaae66\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-shortcode\"><div class=\"trp_language_switcher_shortcode\">\n<div class=\"trp-language-switcher trp-language-switcher-container\" data-no-translation>\n    <div class=\"trp-ls-shortcode-current-language\">\n        <a href=\"#\" class=\"trp-ls-shortcode-disabled-language trp-ls-disabled-language\" title=\"Italiano\" onclick=\"event.preventDefault()\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"trp-flag-image\" src=\"https:\/\/vin.mecalife.com\/wp-content\/plugins\/translatepress-multilingual\/assets\/images\/flags\/it_IT.png\" width=\"18\" height=\"12\" alt=\"it_IT\" title=\"Italiano\"> Italiano\t\t<\/a>\n    <\/div>\n    <div class=\"trp-ls-shortcode-language\">\n                <a href=\"#\" class=\"trp-ls-shortcode-disabled-language trp-ls-disabled-language\"  title=\"Italiano\" onclick=\"event.preventDefault()\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"trp-flag-image\" src=\"https:\/\/vin.mecalife.com\/wp-content\/plugins\/translatepress-multilingual\/assets\/images\/flags\/it_IT.png\" width=\"18\" height=\"12\" alt=\"it_IT\" title=\"Italiano\"> Italiano\t\t<\/a>\n                    <a href=\"https:\/\/vin.mecalife.com\/wp-json\/wp\/v2\/auto\/29021\/\" title=\"Fran\u00e7ais\">\n            <img loading=\"lazy\" decoding=\"async\" class=\"trp-flag-image\" src=\"https:\/\/vin.mecalife.com\/wp-content\/plugins\/translatepress-multilingual\/assets\/images\/flags\/fr_FR.png\" width=\"18\" height=\"12\" alt=\"fr_FR\" title=\"Fran\u00e7ais\"> Fran\u00e7ais        <\/a>\n\n            <a href=\"https:\/\/vin.mecalife.com\/en-us\/wp-json\/wp\/v2\/auto\/29021\/\" title=\"English\">\n            <img loading=\"lazy\" decoding=\"async\" class=\"trp-flag-image\" src=\"https:\/\/vin.mecalife.com\/wp-content\/plugins\/translatepress-multilingual\/assets\/images\/flags\/en_US.png\" width=\"18\" height=\"12\" alt=\"en_US\" title=\"English\"> English        <\/a>\n\n            <a href=\"https:\/\/vin.mecalife.com\/en_au\/wp-json\/wp\/v2\/auto\/29021\/\" title=\"English (Australia)\">\n            <img loading=\"lazy\" decoding=\"async\" class=\"trp-flag-image\" src=\"https:\/\/vin.mecalife.com\/wp-content\/plugins\/translatepress-multilingual\/assets\/images\/flags\/en_AU.png\" width=\"18\" height=\"12\" alt=\"en_AU\" title=\"English (Australia)\"> English (Australia)        <\/a>\n\n            <a href=\"https:\/\/vin.mecalife.com\/en_ca\/wp-json\/wp\/v2\/auto\/29021\/\" title=\"English (Canada)\">\n            <img loading=\"lazy\" decoding=\"async\" class=\"trp-flag-image\" src=\"https:\/\/vin.mecalife.com\/wp-content\/plugins\/translatepress-multilingual\/assets\/images\/flags\/en_CA.png\" width=\"18\" height=\"12\" alt=\"en_CA\" title=\"English (Canada)\"> English (Canada)        <\/a>\n\n            <a href=\"https:\/\/vin.mecalife.com\/en_gb\/wp-json\/wp\/v2\/auto\/29021\/\" title=\"English (UK)\">\n            <img loading=\"lazy\" decoding=\"async\" class=\"trp-flag-image\" src=\"https:\/\/vin.mecalife.com\/wp-content\/plugins\/translatepress-multilingual\/assets\/images\/flags\/en_GB.png\" width=\"18\" height=\"12\" alt=\"en_GB\" title=\"English (UK)\"> English (UK)        <\/a>\n\n            <a href=\"https:\/\/vin.mecalife.com\/en_nz\/wp-json\/wp\/v2\/auto\/29021\/\" title=\"English (New Zealand)\">\n            <img loading=\"lazy\" decoding=\"async\" class=\"trp-flag-image\" src=\"https:\/\/vin.mecalife.com\/wp-content\/plugins\/translatepress-multilingual\/assets\/images\/flags\/en_NZ.png\" width=\"18\" height=\"12\" alt=\"en_NZ\" title=\"English (New Zealand)\"> English (New Zealand)        <\/a>\n\n            <a href=\"https:\/\/vin.mecalife.com\/en_za\/wp-json\/wp\/v2\/auto\/29021\/\" title=\"English (South Africa)\">\n            <img loading=\"lazy\" decoding=\"async\" class=\"trp-flag-image\" src=\"https:\/\/vin.mecalife.com\/wp-content\/plugins\/translatepress-multilingual\/assets\/images\/flags\/en_ZA.png\" width=\"18\" height=\"12\" alt=\"en_ZA\" title=\"English (South Africa)\"> English (South Africa)        <\/a>\n\n            <a href=\"https:\/\/vin.mecalife.com\/de_de\/wp-json\/wp\/v2\/auto\/29021\/\" title=\"Deutsch (Sie)\">\n            <img loading=\"lazy\" decoding=\"async\" class=\"trp-flag-image\" src=\"https:\/\/vin.mecalife.com\/wp-content\/plugins\/translatepress-multilingual\/assets\/images\/flags\/de_DE_formal.png\" width=\"18\" height=\"12\" alt=\"de_DE_formal\" title=\"Deutsch (Sie)\"> Deutsch (Sie)        <\/a>\n\n            <a href=\"https:\/\/vin.mecalife.com\/es_es\/wp-json\/wp\/v2\/auto\/29021\/\" title=\"Espa\u00f1ol\">\n            <img loading=\"lazy\" decoding=\"async\" class=\"trp-flag-image\" src=\"https:\/\/vin.mecalife.com\/wp-content\/plugins\/translatepress-multilingual\/assets\/images\/flags\/es_ES.png\" width=\"18\" height=\"12\" alt=\"es_ES\" title=\"Espa\u00f1ol\"> Espa\u00f1ol        <\/a>\n\n            <a href=\"https:\/\/vin.mecalife.com\/fr_be\/wp-json\/wp\/v2\/auto\/29021\/\" title=\"Fran\u00e7ais de Belgique\">\n            <img loading=\"lazy\" decoding=\"async\" class=\"trp-flag-image\" src=\"https:\/\/vin.mecalife.com\/wp-content\/plugins\/translatepress-multilingual\/assets\/images\/flags\/fr_BE.png\" width=\"18\" height=\"12\" alt=\"fr_BE\" title=\"Fran\u00e7ais de Belgique\"> Fran\u00e7ais de Belgique        <\/a>\n\n            <a href=\"https:\/\/vin.mecalife.com\/nl_be\/wp-json\/wp\/v2\/auto\/29021\/\" title=\"Nederlands (Belgi\u00eb)\">\n            <img loading=\"lazy\" decoding=\"async\" class=\"trp-flag-image\" src=\"https:\/\/vin.mecalife.com\/wp-content\/plugins\/translatepress-multilingual\/assets\/images\/flags\/nl_BE.png\" width=\"18\" height=\"12\" alt=\"nl_BE\" title=\"Nederlands (Belgi\u00eb)\"> Nederlands (Belgi\u00eb)        <\/a>\n\n            <a href=\"https:\/\/vin.mecalife.com\/de_ch\/wp-json\/wp\/v2\/auto\/29021\/\" title=\"Deutsch (Schweiz)\">\n            <img loading=\"lazy\" decoding=\"async\" class=\"trp-flag-image\" src=\"https:\/\/vin.mecalife.com\/wp-content\/plugins\/translatepress-multilingual\/assets\/images\/flags\/de_CH.png\" width=\"18\" height=\"12\" alt=\"de_CH\" title=\"Deutsch (Schweiz)\"> Deutsch (Schweiz)        <\/a>\n\n        <\/div>\n    <script type=\"application\/javascript\">\n        \/\/ need to have the same with set from JS on both divs. Otherwise it can push stuff around in HTML\n        var trp_ls_shortcodes = document.querySelectorAll('.trp_language_switcher_shortcode .trp-language-switcher');\n        if ( trp_ls_shortcodes.length > 0) {\n            \/\/ get the last language switcher added\n            var trp_el = trp_ls_shortcodes[trp_ls_shortcodes.length - 1];\n\n            var trp_shortcode_language_item = trp_el.querySelector( '.trp-ls-shortcode-language' )\n            \/\/ set width\n            var trp_ls_shortcode_width                                               = trp_shortcode_language_item.offsetWidth + 16;\n            trp_shortcode_language_item.style.width                                  = trp_ls_shortcode_width + 'px';\n            trp_el.querySelector( '.trp-ls-shortcode-current-language' ).style.width = trp_ls_shortcode_width + 'px';\n\n            \/\/ We're putting this on display: none after we have its width.\n            trp_shortcode_language_item.style.display = 'none';\n        }\n    <\/script>\n<\/div>\n<\/div><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-459864e\" data-id=\"459864e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ea11fc0 elementor-widget elementor-widget-image\" data-id=\"ea11fc0\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"200\" height=\"56\" src=\"https:\/\/vin.mecalife.com\/wp-content\/uploads\/2020\/06\/mecavin_logo.svg\" class=\"attachment-full size-full wp-image-20885\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-18b597c\" data-id=\"18b597c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d82bebc elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"d82bebc\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/vin.mecalife.com\/it_it\/avvisi-legali\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Informazioni legali<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9c166b8 elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"9c166b8\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/vin.mecalife.com\/it_it\/cgv\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">GTC<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5136acd elementor-mobile-align-center elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-button\" data-id=\"5136acd\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/vin.mecalife.com\/it_it\/contact\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Contatto<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0390303 elementor-mobile-align-center elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-button\" data-id=\"0390303\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/vin.mecalife.com\/it_it\/compte\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Conto<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4855180 elementor-section-content-top elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4855180\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cb6c046\" data-id=\"cb6c046\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fe42f06 elementor-widget elementor-widget-text-editor\" data-id=\"fe42f06\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.22.0 - 26-06-2024 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p>2018 &#8211; 2024 &#8211; Tous droits r\u00e9serv\u00e9s SAS MECALIFE\u00a0<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9abbeb2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9abbeb2\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1d2f839\" data-id=\"1d2f839\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1467412 elementor-mobile-button-align-stretch elementor-hidden-desktop elementor-hidden-tablet elementor-button-align-stretch elementor-widget elementor-widget-form\" data-id=\"1467412\" data-element_type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;Suivant&quot;,&quot;step_previous_label&quot;:&quot;Pr\\u00e9c\\u00e9dent&quot;,&quot;sticky&quot;:&quot;bottom&quot;,&quot;button_width&quot;:&quot;100&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;,&quot;sticky_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;sticky_offset&quot;:0,&quot;sticky_effects_offset&quot;:0}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" name=\"Nouveau formulaire\" action=\"\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"20911\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"1467412\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"MecaVIN FR\" \/>\n\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text\">\n\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[field_c031dad]\" id=\"form-field-field_c031dad\" class=\"elementor-field elementor-size-sm\" style=\"display:none !important;\">\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-hidden elementor-field-group elementor-column elementor-field-group-idaff elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"hidden\" name=\"form_fields[idaff]\" id=\"form-field-idaff\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" value=\"3\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-hidden elementor-field-group elementor-column elementor-field-group-src elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"hidden\" name=\"form_fields[src]\" id=\"form-field-src\" class=\"elementor-field elementor-size-sm  elementor-field-textual\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button class=\"elementor-button elementor-size-sm\" type=\"submit\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Obtenir le Rapport<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<input type=\"hidden\" name=\"trp-form-language\" value=\"it_it\"\/><\/form>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"featured_media":0,"template":"elementor_canvas","modele":[390],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u25b7 Identification Finition DACIA LODGY 2012 2019 ! Decode VIN<\/title>\n<meta name=\"description\" content=\"V\u00e9rifier la Liste d&#039;Option d&#039;Origine et Finition du V\u00e9hicule DACIA LODGY 2012 2019 que vous d\u00e9sirez acheter. A partir du num\u00e9ro de s\u00e9rie \/ Code VIN ou immatriculation.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vin.mecalife.com\/it_it\/auto\/finition-dacia-lodgy-2012-2019\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u25b7 Identification Finition DACIA LODGY 2012 2019 ! Decode VIN\" \/>\n<meta property=\"og:description\" content=\"V\u00e9rifier la Liste d&#039;Option d&#039;Origine et Finition du V\u00e9hicule DACIA LODGY 2012 2019 que vous d\u00e9sirez acheter. A partir du num\u00e9ro de s\u00e9rie \/ Code VIN ou immatriculation.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vin.mecalife.com\/it_it\/auto\/finition-dacia-lodgy-2012-2019\/\" \/>\n<meta property=\"og:site_name\" content=\"MecaVIN FR\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vin.mecalife.com\/wp-content\/uploads\/2021\/09\/mecavin_identification-voiture_acheteur.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"39 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/vin.mecalife.com\/auto\/finition-dacia-lodgy-2012-2019\/\",\"url\":\"https:\/\/vin.mecalife.com\/auto\/finition-dacia-lodgy-2012-2019\/\",\"name\":\"\u25b7 Identification Finition DACIA LODGY 2012 2019 ! Decode VIN\",\"isPartOf\":{\"@id\":\"https:\/\/vin.mecalife.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/vin.mecalife.com\/auto\/finition-dacia-lodgy-2012-2019\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/vin.mecalife.com\/auto\/finition-dacia-lodgy-2012-2019\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/vin.mecalife.com\/wp-content\/uploads\/2021\/09\/mecavin_identification-voiture_acheteur.jpg\",\"datePublished\":\"2019-07-27T06:19:47+00:00\",\"dateModified\":\"2019-07-27T06:19:47+00:00\",\"description\":\"V\u00e9rifier la Liste d'Option d'Origine et Finition du V\u00e9hicule DACIA LODGY 2012 2019 que vous d\u00e9sirez acheter. A partir du num\u00e9ro de s\u00e9rie \/ Code VIN ou immatriculation.\",\"breadcrumb\":{\"@id\":\"https:\/\/vin.mecalife.com\/auto\/finition-dacia-lodgy-2012-2019\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/vin.mecalife.com\/auto\/finition-dacia-lodgy-2012-2019\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/vin.mecalife.com\/auto\/finition-dacia-lodgy-2012-2019\/#primaryimage\",\"url\":\"https:\/\/vin.mecalife.com\/wp-content\/uploads\/2021\/09\/mecavin_identification-voiture_acheteur.jpg\",\"contentUrl\":\"https:\/\/vin.mecalife.com\/wp-content\/uploads\/2021\/09\/mecavin_identification-voiture_acheteur.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/vin.mecalife.com\/auto\/finition-dacia-lodgy-2012-2019\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/vin.mecalife.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Finition DACIA LODGY 2012 2019\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/vin.mecalife.com\/#website\",\"url\":\"https:\/\/vin.mecalife.com\/\",\"name\":\"MecaVIN FR\",\"description\":\"Identifier votre v\u00e9hicule avec immatriculation ou VIN - Options d&#039;\u00e9quipements - Code Couleur - Type Moteur - Type Boite\",\"publisher\":{\"@id\":\"https:\/\/vin.mecalife.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/vin.mecalife.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/vin.mecalife.com\/#organization\",\"name\":\"MecaVIN by MecaLIFE\",\"url\":\"https:\/\/vin.mecalife.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/vin.mecalife.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/vin.mecalife.com\/wp-content\/uploads\/2020\/06\/mecavin_logo.svg\",\"contentUrl\":\"https:\/\/vin.mecalife.com\/wp-content\/uploads\/2020\/06\/mecavin_logo.svg\",\"width\":200,\"height\":56,\"caption\":\"MecaVIN by MecaLIFE\"},\"image\":{\"@id\":\"https:\/\/vin.mecalife.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u25b7 Identification Finition DACIA LODGY 2012 2019 ! Decode VIN","description":"V\u00e9rifier la Liste d'Option d'Origine et Finition du V\u00e9hicule DACIA LODGY 2012 2019 que vous d\u00e9sirez acheter. A partir du num\u00e9ro de s\u00e9rie \/ Code VIN ou immatriculation.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vin.mecalife.com\/it_it\/auto\/finition-dacia-lodgy-2012-2019\/","og_locale":"it_IT","og_type":"article","og_title":"\u25b7 Identification Finition DACIA LODGY 2012 2019 ! Decode VIN","og_description":"V\u00e9rifier la Liste d'Option d'Origine et Finition du V\u00e9hicule DACIA LODGY 2012 2019 que vous d\u00e9sirez acheter. A partir du num\u00e9ro de s\u00e9rie \/ Code VIN ou immatriculation.","og_url":"https:\/\/vin.mecalife.com\/it_it\/auto\/finition-dacia-lodgy-2012-2019\/","og_site_name":"MecaVIN FR","og_image":[{"url":"https:\/\/vin.mecalife.com\/wp-content\/uploads\/2021\/09\/mecavin_identification-voiture_acheteur.jpg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"39 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/vin.mecalife.com\/auto\/finition-dacia-lodgy-2012-2019\/","url":"https:\/\/vin.mecalife.com\/auto\/finition-dacia-lodgy-2012-2019\/","name":"\u25b7 Identification Finition DACIA LODGY 2012 2019 ! Decode VIN","isPartOf":{"@id":"https:\/\/vin.mecalife.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vin.mecalife.com\/auto\/finition-dacia-lodgy-2012-2019\/#primaryimage"},"image":{"@id":"https:\/\/vin.mecalife.com\/auto\/finition-dacia-lodgy-2012-2019\/#primaryimage"},"thumbnailUrl":"https:\/\/vin.mecalife.com\/wp-content\/uploads\/2021\/09\/mecavin_identification-voiture_acheteur.jpg","datePublished":"2019-07-27T06:19:47+00:00","dateModified":"2019-07-27T06:19:47+00:00","description":"V\u00e9rifier la Liste d'Option d'Origine et Finition du V\u00e9hicule DACIA LODGY 2012 2019 que vous d\u00e9sirez acheter. A partir du num\u00e9ro de s\u00e9rie \/ Code VIN ou immatriculation.","breadcrumb":{"@id":"https:\/\/vin.mecalife.com\/auto\/finition-dacia-lodgy-2012-2019\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vin.mecalife.com\/auto\/finition-dacia-lodgy-2012-2019\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/vin.mecalife.com\/auto\/finition-dacia-lodgy-2012-2019\/#primaryimage","url":"https:\/\/vin.mecalife.com\/wp-content\/uploads\/2021\/09\/mecavin_identification-voiture_acheteur.jpg","contentUrl":"https:\/\/vin.mecalife.com\/wp-content\/uploads\/2021\/09\/mecavin_identification-voiture_acheteur.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/vin.mecalife.com\/auto\/finition-dacia-lodgy-2012-2019\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/vin.mecalife.com\/"},{"@type":"ListItem","position":2,"name":"Finition DACIA LODGY 2012 2019"}]},{"@type":"WebSite","@id":"https:\/\/vin.mecalife.com\/#website","url":"https:\/\/vin.mecalife.com\/","name":"MecaVIN FR","description":"Identifier votre v\u00e9hicule avec immatriculation ou VIN - Options d&#039;\u00e9quipements - Code Couleur - Type Moteur - Type Boite","publisher":{"@id":"https:\/\/vin.mecalife.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vin.mecalife.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/vin.mecalife.com\/#organization","name":"MecaVIN by MecaLIFE","url":"https:\/\/vin.mecalife.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/vin.mecalife.com\/#\/schema\/logo\/image\/","url":"https:\/\/vin.mecalife.com\/wp-content\/uploads\/2020\/06\/mecavin_logo.svg","contentUrl":"https:\/\/vin.mecalife.com\/wp-content\/uploads\/2020\/06\/mecavin_logo.svg","width":200,"height":56,"caption":"MecaVIN by MecaLIFE"},"image":{"@id":"https:\/\/vin.mecalife.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/vin.mecalife.com\/it_it\/wp-json\/wp\/v2\/auto\/29021"}],"collection":[{"href":"https:\/\/vin.mecalife.com\/it_it\/wp-json\/wp\/v2\/auto"}],"about":[{"href":"https:\/\/vin.mecalife.com\/it_it\/wp-json\/wp\/v2\/types\/auto"}],"version-history":[{"count":0,"href":"https:\/\/vin.mecalife.com\/it_it\/wp-json\/wp\/v2\/auto\/29021\/revisions"}],"wp:attachment":[{"href":"https:\/\/vin.mecalife.com\/it_it\/wp-json\/wp\/v2\/media?parent=29021"}],"wp:term":[{"taxonomy":"modele","embeddable":true,"href":"https:\/\/vin.mecalife.com\/it_it\/wp-json\/wp\/v2\/modele?post=29021"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}